{"id":118567,"date":"2020-04-11T01:04:18","date_gmt":"2020-04-11T01:04:18","guid":{"rendered":"legacy-k2-2019-95572"},"modified":"2020-04-11T01:04:18","modified_gmt":"2020-04-11T01:04:18","slug":"cae-35-venta-de-vehiculos-nuevos-en-puebla-y-tlaxcala-por-covid-19-k2-95572","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2020\/estado\/cae-35-venta-de-vehiculos-nuevos-en-puebla-y-tlaxcala-por-covid-19-k2-95572\/118567\/","title":{"rendered":"Cae 35% venta de veh\u00edculos nuevos en Puebla y Tlaxcala por COVID-19"},"content":{"rendered":"<p>Por el COVID19 uno de los sectores m\u00e1s golpeados son las agencias de venta de autos nuevos, las cuales han disminuido sus ventas 35 por ciento, as\u00ed lo dio a conocer Erika Orozco Osorio, directora de la Asociaci\u00f3n Mexicana de Distribuci\u00f3n de Autom\u00f3viles del Estado de Puebla y Tlaxcala<\/p>\n<p>Por el COVID19 uno de los sectores m\u00e1s golpeados son las agencias de venta de autos nuevos, las cuales han disminuido sus ventas 35 por ciento, as\u00ed lo dio a conocer Erika Orozco Osorio, directora de la Asociaci\u00f3n Mexicana de Distribuci\u00f3n de Autom\u00f3viles del Estado de Puebla y Tlaxcala (AMDA).\u00a0<\/p>\n<p>Revel\u00f3 que desde el inicio del a\u00f1o se han tenido complicaciones para vender veh\u00edculos de todas las marcas, ya que tan solo sumaron 4 mil 875 unidades comercializadas entre enero y febrero.<\/p>\n<p>Por tanto, indic\u00f3 que se espera una reducci\u00f3n significativa y afectaciones en las agencias durante marzo y abril, debido a la cuarentena que se vive por la contingencia sanitaria, \u201cno estamos vendiendo, la gente a permanecido en sus casas para evitar contagiarse, lo cual es lo correcto, por tanto no tenemos ingreso de clientes en las agencias\u201d.<\/p>\n<p>Las unidades que se han vendido en el primer bimestre del a\u00f1o son: Buick_Gmc\u00a0 con 21 unidades, Chevrolet\u00a0 mil 230 veh\u00edculos, Chrysler 235, Volkswagen 572, Fiat 25, Ford 259, Honda 68, Hyundai 159, Mazda 314, Mercedes Benz 22, Nissan mil 33, Renault 255, Seat 130, Susuki 105 y Kia solo tuvo ventas en febrero registrando 71.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por el COVID19 uno de los sectores m\u00e1s golpeados son las agencias de venta de autos nuevos, las cuales han disminuido sus ventas 35 por ciento, as\u00ed lo dio a conocer Erika Orozco Osorio, directora de la Asociaci\u00f3n Mexicana de Distribuci\u00f3n de Autom\u00f3viles del Estado de Puebla y Tlaxcala Por el COVID19 uno de los [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":134609,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[78],"tags":[],"class_list":["post-118567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/118567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=118567"}],"version-history":[{"count":0,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/118567\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media\/134609"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=118567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=118567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=118567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}