{"id":124954,"date":"2019-10-20T16:40:11","date_gmt":"2019-10-20T16:40:11","guid":{"rendered":"legacy-k2-2019-88169"},"modified":"2019-10-20T16:40:11","modified_gmt":"2019-10-20T16:40:11","slug":"volvo-xc40-recharge-2020-el-primer-electrico-de-la-marca-k2-88169","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2019\/autos\/volvo-xc40-recharge-2020-el-primer-electrico-de-la-marca-k2-88169\/124954\/","title":{"rendered":"Volvo XC40 Recharge 2020, el primer el\u00e9ctrico de la marca"},"content":{"rendered":"<p>AutoCosmos informa que no electric, no ev, no plug-in ni nada de eso. Recharge. Ese ser\u00e1 el apellido con el que conocer\u00e1s a todos los futuros Volvo electrificados (h\u00edbridos incluidos), partiendo por la nueva XC40 Recharge, que es el primer auto 100% el\u00e9ctrico de la marca de producci\u00f3n masiva (obviando experimentos como el C30 Electric DRIVe).<\/p>\n<p>Este auto no solo viene con la primicia de las bater\u00edas, sino que, adem\u00e1s, como contamos hace poco, es el primer auto del mundo en utilizar el sistema de infoentretenimiento Android Automotive OS de Google, lo que le permite ganar acceso nativo a aplicaciones como Google Assistant, Google Maps o Google Play Store. Incluso, se podr\u00e1 actualizar solo, tal como un celular.<\/p>\n<p>La idea de los suecos, es durante los pr\u00f3ximos cinco a\u00f1os, ir lanzando todos los a\u00f1os un modelo el\u00e9ctrico nuevo, para as\u00ed tratar de alcanzar la meta de un line-up 50% el\u00e9ctrico y 50% hibrido hacia el 2025. Volvo espera lograr con su oferta electrificada el mismo efecto que lograron con el tema de la seguridad, hacerlo un atributo clave de venta. Incluso, seg\u00fan reza el comunicado de prensa, Volvo comenzar\u00e1 el 2020 con estrategias agresivas que permitan posicionar m\u00e1s esta idea de cambiarse a un auto a bater\u00eda. Por ejemplo, la p\u00e1gina web de Volvo te preguntar\u00e1 antes que cualquier cosa si quieres un modelo Recharge o no. Incluso, si compras un modelo Recharge, te ofrecer\u00e1n un a\u00f1o gratis de recarga, donde al cliente le ser\u00e1 abonado el costo promedio de lo gastado en ese periodo.<\/p>\n<p>La nueva XC40 Recharge emplea un tren motriz AWD, con dos motores el\u00e9ctricos, uno en cada eje. Ambos, logran una potencia de 304 kilowatts (o 408 Hp) y un torque total de 487 lb-pie. Las bater\u00edas est\u00e1n ubicadas en el suelo del auto, tiene una capacidad de 78 kWh y por su ubicaci\u00f3n, ayudan a bajar el centro de gravedad, propiciando un manejo mucho m\u00e1s estable, entretenido y seguro. El pack de bater\u00edas se encuentra en una estructura de aluminio extruido, con zonas espec\u00edficas para disipar impactos. El XC40 Recharge deber\u00eda recorrer 400 kil\u00f3metros sin problemas en una sola carga. Despu\u00e9s, puedes pasar a una electrolinera y reponer el 80% de su capacidad en 40 minutos.<\/p>\n<p>Como el motor el\u00e9ctrico frontal es m\u00e1s peque\u00f1o que uno convencional, se libera espacio para una conveniente &#8220;segunda&#8221;cajuela, donde podr\u00e1s guardar un par de bolsos. Aunque claro, Volvo tambi\u00e9n ha reforzado esta zona para mantener un alto est\u00e1ndar de absorci\u00f3n de impactos. En el caso del motor trasero, este fue concebido para que sea parte de la estructura del auto, cosa que participe en la absorci\u00f3n de impactos.<\/p>\n<p>Para satisfacer el crecimiento anticipado de la demanda de sus autom\u00f3viles Recharge, Volvo Cars triplicar\u00e1 la capacidad de producci\u00f3n de autom\u00f3viles electrificados y, a partir del pr\u00f3ximo a\u00f1o, preparar\u00e1 una selecci\u00f3n Designer&#8217;s Choice con preconfiguraciones sugeridas, con el fin de tener m\u00e1s de esos autos en la linea de ensamblaje y mejorar los tiempos de entrega.<\/p>\n<p>\u00bfY el resto?<\/p>\n<p>Con respecto a la XC40 a gasolina,\u00a0 est\u00e9ticamente solo vemos cambios en la parrilla, la cual, en lugar de tener entradas de aire, viene casi sellada con un panel que hace juego con el color de la carrocer\u00eda. El interior, salvo por el cambio en el sistema de infoentretenimiento, sigue contando con los mismos beneficios que encontramos en el modelo que actualmente se comercializa en M\u00e9xico.\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AutoCosmos informa que no electric, no ev, no plug-in ni nada de eso. Recharge. Ese ser\u00e1 el apellido con el que conocer\u00e1s a todos los futuros Volvo electrificados (h\u00edbridos incluidos), partiendo por la nueva XC40 Recharge, que es el primer auto 100% el\u00e9ctrico de la marca de producci\u00f3n masiva (obviando experimentos como el C30 Electric [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":160009,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[87],"tags":[],"class_list":["post-124954","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autos","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/124954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=124954"}],"version-history":[{"count":0,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/124954\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media\/160009"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=124954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=124954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=124954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}