{"id":390439,"date":"2011-03-16T02:41:16","date_gmt":"2011-03-16T02:41:16","guid":{"rendered":"legacy-k2-2009-10501"},"modified":"2011-03-16T02:41:16","modified_gmt":"2011-03-16T02:41:16","slug":"conductor-lesionado-por-querer-ganar-el-paso-al-tren-k2-10501","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/conductor-lesionado-por-querer-ganar-el-paso-al-tren-k2-10501\/390439\/","title":{"rendered":"Se lo llev\u00f3 el tren en la carretera federal a Tlaxcala, sali\u00f3 ileso"},"content":{"rendered":"<div>Conductor de un autom\u00f3vil Tsuru, color blanco y placas de circulaci\u00f3n 409-XNX, del Distrito Federal se llev\u00f3 el susto de su vida luego de que saliera de la unidad instantes antes de que fuera arrollado por una m\u00e1quina de Ferrosur, n\u00f9mero 14506, al intentar ganarle el paso<\/div>\n<div>&#160;<\/div>\n<div><\/div>\n<div>&#160;<\/div>\n<div>Conductor de un autom\u00f3vil Tsuru, color blanco y placas de circulaci\u00f3n 409-XNX, del Distrito Federal se llev\u00f3 el susto de su vida luego de que saliera de la unidad instantes antes de que fuera arrollado por una m\u00e1quina de Ferrosur, n\u00f9mero 14506, al intentar ganarle el paso<\/div>\n<div>\n&#160;<\/div>\n<div>Los hechos se registraron alrededor de las 8.30 horas en el&#160;kil\u00f3metro 7.5 de la federal a Tlaxcala en la Colonia Ignacio Mariscal. Param\u00e9dicos de Cruz Roja acudieron al lugar donde atendieron al conductor del veh\u00edculo quese encontraba asustado, en tanto, elementos de Protecci\u00f3n Civil resguardaron el lugar durante varios minutos.<\/div>\n<div>&#160;<\/div>\n<div>\n&#160;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Conductor de un autom\u00f3vil Tsuru, color blanco y placas de circulaci\u00f3n 409-XNX, del Distrito Federal se llev\u00f3 el susto de su vida luego de que saliera de la unidad instantes antes de que fuera arrollado por una m\u00e1quina de Ferrosur, n\u00f9mero 14506, al intentar ganarle el paso &#160; &#160; Conductor de un autom\u00f3vil Tsuru, color [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":422703,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390439","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390439"}],"version-history":[{"count":0,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390439\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media\/422703"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}