{"id":390441,"date":"2011-03-16T03:20:24","date_gmt":"2011-03-16T03:20:24","guid":{"rendered":"http:\/\/legacy-k2-2009-10503"},"modified":"2026-03-27T18:04:22","modified_gmt":"2026-03-28T00:04:22","slug":"rmv-indispensable-la-fusion-gobierno-empresas-y-ciudadania-para-el-desarrollo-del-estado-k2-10503","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/rmv-indispensable-la-fusion-gobierno-empresas-y-ciudadania-para-el-desarrollo-del-estado-k2-10503\/390441\/","title":{"rendered":"Comex pintar\u00e1 mil fachadas en la ciudad de Puebla junto con el gobierno"},"content":{"rendered":"<div>El Gobernador de Puebla Rafael Moreno Valle asegur\u00f3 que para lograr las grandes transformaciones, realizar cambios y enfrentar obst\u00e1culos se requiere de la suma de esfuerzos del gobierno, empresas y ciudadan\u00eda.<\/div>\n<div>\n&#160;<\/div>\n<div>Moreno Valle destac\u00f3 las ventajas geogr\u00e1ficas y de comunicaci\u00f3n, con las que cuenta el estado, como elementos vitales para la atracci\u00f3n de nuevas inversiones.<\/div>\n<div>\n&#160;<\/div>\n<div>Afirm\u00f3 que esta generaci\u00f3n enfrenta hoy retos complejos como el cambio clim\u00e1tico, desastres naturales y escasez de alimentos.<\/div>\n<div>\n&#160;<\/div>\n<div>Al intervenir en la Convenci\u00f3n de COMEX, que se desarrolla en el Complejo Cultural Universitario, &#160;Moreno Valle reconoci\u00f3 el liderazgo de esta empresa mexicana global y de calidad mundial.<\/div>\n<div>\n&#160;<\/div>\n<div>Inform\u00f3 que el Gobierno estatal tiene contemplado con la fundaci\u00f3n Comex &#160;pintar mil fachadas en la ciudad de Puebla y construir 500 casas en municipios pobres del estado.<\/div>\n<div>\n&#160;<\/div>\n<div>El Gobernador Rafael Moreno Valle estuvo acompa\u00f1ado de &#160;Alfredo Achar Tussie, presidente del Consejo de Grupo Comex y Pablo Rodr\u00edguez Regordosa, secretario de &#160;Desarrollo Econ\u00f3mico.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Gobernador de Puebla Rafael Moreno Valle asegur\u00f3 que para lograr las grandes transformaciones, realizar cambios y enfrentar obst\u00e1culos se requiere de la suma de esfuerzos del gobierno, empresas y ciudadan\u00eda. &#160; Moreno Valle destac\u00f3 las ventajas geogr\u00e1ficas y de comunicaci\u00f3n, con las que cuenta el estado, como elementos vitales para la atracci\u00f3n de nuevas [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390441","post","type-post","status-publish","format-standard","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390441"}],"version-history":[{"count":1,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390441\/revisions"}],"predecessor-version":[{"id":428752,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390441\/revisions\/428752"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}