{"id":390456,"date":"2011-03-16T13:55:49","date_gmt":"2011-03-16T13:55:49","guid":{"rendered":"legacy-k2-2009-10518"},"modified":"2011-03-16T13:55:49","modified_gmt":"2011-03-16T13:55:49","slug":"aviones-no-tripulados-de-eu-sobrevuelan-territorio-mexicano-k2-10518","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/aviones-no-tripulados-de-eu-sobrevuelan-territorio-mexicano-k2-10518\/390456\/","title":{"rendered":"Aviones no tripulados de EU sobrevuelan territorio mexicano"},"content":{"rendered":"<p>La cooperaci\u00f3n militar entre Estados Unidos y M\u00e9xico se ha profundizado con el sobrevuelo del territorio mexicano por aviones no tripulados estadounidenses como parte de un acuerdo de lucha contra el narcotr\u00e1fico, inform\u00f3 hoy el New York Times.<\/p>\n<p>Otro de los acuerdos es la creaci\u00f3n de un centro de fusi\u00f3n &#8220;antinarc\u00f3ticos&#8221; en M\u00e9xico, en el que trabajar\u00edan conjuntamente las autoridades de los dos pa\u00edses.<\/p>\n<p>El diario estadounidense se\u00f1ala que los vuelos de reconocimiento, en operaci\u00f3n desde el pasado mes, buscan aportar m\u00e1s informaci\u00f3n a las autoridades mexicanas sobre la actuaci\u00f3n y ubicaci\u00f3n de las organizaciones narcotraficantes en M\u00e9xico.<\/p>\n<p>Seg\u00fan el diario, que cita a fuentes oficiales del Pent\u00e1gono, aunque no da nombres, los vuelos del Departamento de Seguridad Nacional de EU son fruto de varios acuerdos bilaterales alcanzados tras la reuni\u00f3n sostenida por los presidentes de ambos pa\u00edses, Barack Obama y Felipe Calder\u00f3n, en Washington el pasado 3 de marzo.<\/p>\n<p>Gracias a estos vuelos se ha podido localizar a varios sospechosos vinculados con el asesinato del agente estadounidenses de Inmigraci\u00f3n y Aduanas, Jaime Zapata, el pasado 15 de febrero, indicaron estas mismas fuentes.<\/p>\n<p>Los vuelos son realizados por los aviones no tripulados Global Hawk, unos aparatos que vuelan a m\u00e1s de 10 mil metros de altitud y que no pueden ser vistos desde tierra, y tienen como objetivo localizar las redes de narcotraficantes mexicanos.<\/p>\n<p>Este acuerdo entre M\u00e9xico y EU se hab\u00eda mantenido en secreto debido a las restricciones legales en M\u00e9xico y la sensibilidad pol\u00edtica del tema respecto a cuestiones de soberan\u00eda. <br \/>\n&#160;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cooperaci\u00f3n militar entre Estados Unidos y M\u00e9xico se ha profundizado con el sobrevuelo del territorio mexicano por aviones no tripulados estadounidenses como parte de un acuerdo de lucha contra el narcotr\u00e1fico, inform\u00f3 hoy el New York Times. Otro de los acuerdos es la creaci\u00f3n de un centro de fusi\u00f3n &#8220;antinarc\u00f3ticos&#8221; en M\u00e9xico, en el [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390456","post","type-post","status-publish","format-standard","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390456"}],"version-history":[{"count":0,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390456\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}