{"id":390465,"date":"2011-03-16T20:38:52","date_gmt":"2011-03-16T20:38:52","guid":{"rendered":"http:\/\/legacy-k2-2009-10527"},"modified":"2026-03-27T18:04:29","modified_gmt":"2026-03-28T00:04:29","slug":"vazquez-mota-se-placea-por-puebla-k2-10527","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/vazquez-mota-se-placea-por-puebla-k2-10527\/390465\/","title":{"rendered":"V\u00e1zquez Mota hace campa\u00f1a en Puebla"},"content":{"rendered":"<p>La diputada federal panista, Josefina V\u00e1zquez Mota, estuvo en Puebla para sostener reuniones con el gobernador, Rafael Moreno Valle; el edil capitalino, Eduardo Rivera; as\u00ed como con diputados locales y militantes del blanquiazul<\/p>\n<p>Aunque rechaz\u00f3 que su visita a Puebla est\u00e9 relacionada con su inter\u00e9s de contender por la presidencia de la Rep\u00fablica en 2012, la diputada federal del Partido Acci\u00f3n Nacional (PAN), Josefina V\u00e1zquez Mota, se reuni\u00f3 este mi\u00e9rcoles con el gobernador Rafael Moreno&#160;Valle,&#160;el alcalde capitalino, Eduardo Rivera P\u00e9rez, y diputados locales y federales.<\/p>\n<p>V\u00e1zquez Mota justific\u00f3 la visita al se\u00f1alar que sus acciones son la respuesta a la &#8220;demanda que existe por parte de la ciudadan\u00eda&#8221;, respecto a la cercan\u00eda con los legisladores, de ah\u00ed que se d\u00e9 a la tarea de realizar visitas y reuniones con gobernadores de diferentes estados y partidos, adem\u00e1s de alcaldes y organismos privados.<\/p>\n<p>No obstante, reconoci\u00f3 que si su partido la toma en cuenta tendr\u00e1 una plataforma que convoque a miles y miles de mexicanos, y ser\u00e1 Puebla un lugar donde tambi\u00e9n llegar\u00e1n sus propuestas.<\/p>\n<p>Por la tarde, se reuni\u00f3 con un centenar de militantes del blanquiazul ante quienes reconoci\u00f3 su inter\u00e9s por ser candidata a la presidencia de la rep\u00fablica en 2012, y a quienes les pidi\u00f3 abonar a la unidad del PAN.<br \/>\n&#160;<\/p>\n<p><img decoding=\"async\" border=\"0\" alt=\"\" src=\"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-content\/uploads\/joomla\/2009\/portal\/images\/stories\/principal\/MARZO11\/josefina1.JPG\" \/>&#160;<\/p>\n<p>&#160;<img decoding=\"async\" border=\"0\" alt=\"\" src=\"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-content\/uploads\/joomla\/2009\/portal\/images\/stories\/principal\/MARZO11\/joseoki.JPG\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La diputada federal panista, Josefina V\u00e1zquez Mota, estuvo en Puebla para sostener reuniones con el gobernador, Rafael Moreno Valle; el edil capitalino, Eduardo Rivera; as\u00ed como con diputados locales y militantes del blanquiazul Aunque rechaz\u00f3 que su visita a Puebla est\u00e9 relacionada con su inter\u00e9s de contender por la presidencia de la Rep\u00fablica en 2012, [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":422694,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390465"}],"version-history":[{"count":1,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390465\/revisions"}],"predecessor-version":[{"id":428774,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390465\/revisions\/428774"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media\/422694"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}