{"id":390466,"date":"2011-03-16T23:25:15","date_gmt":"2011-03-16T23:25:15","guid":{"rendered":"http:\/\/legacy-k2-2009-10528"},"modified":"2026-03-27T18:04:29","modified_gmt":"2026-03-28T00:04:29","slug":"lo-tiro-un-camion-loma-bella-y-murio-en-el-hospital-k2-10528","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/lo-tiro-un-camion-loma-bella-y-murio-en-el-hospital-k2-10528\/390466\/","title":{"rendered":"Lo tir\u00f3 un cami\u00f3n Loma Bella y muri\u00f3 en el hospital"},"content":{"rendered":"<div>Hombre que cay\u00f3 de un cami\u00f3n de transporte p\u00fablico de la Ruta Loma Bella perdi\u00f3 la vida en el Hospital de Traumatolog\u00eda y Ortopedia del IMSS debido a las lesiones craneoencef\u00e1licas que presentaba.<\/div>\n<div>\u00a0<\/div>\n<div>El occiso respondi\u00f3 al nombre de Ricardo Hern\u00e1ndez Serrano, de 38 a\u00f1os de edad, quien la ma\u00f1ana del martes viajaba a bordo del cami\u00f3n de la Ruta Loma Bella, unidad 2, cuando al parecer debido a un frenado de la unidad provoc\u00f3 que cayera de la unidad cuando circulaba a la altura del Bulevar Xonaca.<\/div>\n<div>\u00a0<\/div>\n<div>Tras recibir atenci\u00f3n m\u00e9dica, el accidentado fue llevado al hospital de Traumatolog\u00eda y Ortopedia del IMSS donde finalmente pereci\u00f3. Los hechos quedaron asentados en la averiguaci\u00f3n 296\/2011\/ECOTE, donde qued\u00f3 asentado que el chofer se dio a la fuga tras el incidente.<\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hombre que cay\u00f3 de un cami\u00f3n de transporte p\u00fablico de la Ruta Loma Bella perdi\u00f3 la vida en el Hospital de Traumatolog\u00eda y Ortopedia del IMSS debido a las lesiones craneoencef\u00e1licas que presentaba. \u00a0 El occiso respondi\u00f3 al nombre de Ricardo Hern\u00e1ndez Serrano, de 38 a\u00f1os de edad, quien la ma\u00f1ana del martes viajaba a [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390466","post","type-post","status-publish","format-standard","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390466"}],"version-history":[{"count":1,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390466\/revisions"}],"predecessor-version":[{"id":428775,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390466\/revisions\/428775"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}