{"id":390481,"date":"2011-03-17T03:38:29","date_gmt":"2011-03-17T03:38:29","guid":{"rendered":"http:\/\/legacy-k2-2009-10543"},"modified":"2026-03-27T18:04:34","modified_gmt":"2026-03-28T00:04:34","slug":"afi-captura-en-puebla-a-48-personas-acusadas-de-robo-de-cable-telefonico-k2-10543","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/afi-captura-en-puebla-a-48-personas-acusadas-de-robo-de-cable-telefonico-k2-10543\/390481\/","title":{"rendered":"AFI detuvo a 48 personas por robar cables de Telmex en Puebla"},"content":{"rendered":"<div>Elementos de la AFI detuvieron a 48 personas acusadas de robar cables de Telmex que fueron ubicadas en la privada Hidalgo de la colonia Francisco I. Madero, en el municipio de Puebla, j en la empresa denominada Comercializadora de Metales Angel\u00f3polis S.A. de C.V.<\/div>\n<div><\/div>\n<div> \u00a0<\/div>\n<div>\n<div>Elementos de la AFI detuvieron a 48 personas acusadas de robar cables de Telmex que fueron ubicadas en la privada Hidalgo de la colonia Francisco I. Madero, en el municipio de Puebla, j en la empresa denominada Comercializadora de Metales Angel\u00f3polis S.A. de C.V.<\/div>\n<div>\u00a0<\/div>\n<div>El agente del Ministerio P\u00fablico de la Federaci\u00f3n consign\u00f3 ante el Juez D\u00e9cimo de Distrito en Puebla la averiguaci\u00f3n previa AP\/PGR\/PUE\/PUE-VII\/0088\/2011 contra Gabriel Alejandro Sigler Ochoa y 47 personas m\u00e1s, por su presunta responsabilidad en la comisi\u00f3n del delito de robo en las modalidades de posesi\u00f3n y comercializaci\u00f3n de objetos robados, \u00e9sta \u00faltima considerada como delito grave, y por el delito de encubrimiento por receptaci\u00f3n, y adem\u00e1s contra Gabriel Alejandro Sigler Ochoa, por el delito de posesi\u00f3n de cartuchos de uso exclusivo del Ej\u00e9rcito, Armada y Fuerza A\u00e9rea.\u00a0<\/div>\n<div><\/div>\n<div>Con motivo de la denuncia presentada por el apoderado legal de Tel\u00e9fonos de M\u00e9xico, relativa a la existencia de puntos de acopio en que se compraba y vend\u00eda cobre extra\u00eddo del cable propiedad de la empresa que representa, producto de constantes robos los cuales ocasionaron interrupciones del servicio telef\u00f3nico en diferentes municipios del estado; el agente del Ministerio P\u00fablico de la Federaci\u00f3n inici\u00f3 la averiguaci\u00f3n previa respectiva.\u00a0<\/div>\n<div><\/div>\n<div>Derivado del desarrollo de la indagatoria cumpliment\u00f3 una orden de cateo con el apoyo de elementos de la Agencia Federal de Investigaci\u00f3n (AFI), personal pericial y el apoderado legal de Telmex, con peritos habilitados en identificaci\u00f3n de cable de su propiedad en el inmueble ubicado en la privada Hidalgo de la colonia Francisco I. Madero, en el municipio de Puebla, con la raz\u00f3n social &#8220;Comercializadora de Metales Angel\u00f3polis S.A. de C.V.&#8221;.\u00a0<\/div>\n<div>\u00a0<\/div>\n<div>En dicho lugar el Fiscal Federal asegur\u00f3:\u00a0<\/div>\n<div>\u00a0<\/div>\n<div>Dos toneladas 550 kilos 600 gramos de cable de cobre\u00a0<\/div>\n<div>180 gramos de cartuchos organizados para arma de fuego calibre 7.62&#215;51 mm\u00a0<\/div>\n<div>13 veh\u00edculos, entre ellos dos tr\u00e1ileres, una camioneta, una vagoneta, cuatro pick up y cinco montacargas\u00a0<\/div>\n<div>Asimismo, se asegur\u00f3 a las siguientes personas:\u00a0<\/div>\n<div>1.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Gabriel Alejandro Sigler Ochoa (administrador)\u00a0<\/div>\n<div>2.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Irma M\u00e9ndez Mart\u00ednez (jefa de compras)\u00a0<\/div>\n<div>3.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Aquilino Marcos Flores (contador)\u00a0<\/div>\n<div>As\u00ed como empleados administrativos, de seguridad, choferes y obreros de nombres:\u00a0<\/div>\n<div><\/div>\n<div>4.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Juana Lorenzo Ortiz\u00a0<\/div>\n<div>5.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Manuela Tecalero Garc\u00eda\u00a0<\/div>\n<div>6.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Gerardo Portela Enr\u00edquez\u00a0<\/div>\n<div>7.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Sa\u00fal D\u00edaz Bahena\u00a0<\/div>\n<div>8.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Rosalva Maga\u00f1a Jim\u00e9nez\u00a0<\/div>\n<div>9.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Erika Gonz\u00e1lez Mendoza\u00a0<\/div>\n<div>10.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Aldo Mart\u00ednez Bahena\u00a0<\/div>\n<div>11.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Octavio Lezama Gonz\u00e1lez\u00a0<\/div>\n<div>12.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Osvaldo Rocha Fern\u00e1ndez\u00a0<\/div>\n<div>13.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Ra\u00fal Padilla Minor\u00a0<\/div>\n<div>14.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Alejandro Honorato Gonz\u00e1lez\u00a0<\/div>\n<div>15.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Ram\u00f3n Guti\u00e9rrez Reyes\u00a0<\/div>\n<div>16.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Miguel Hern\u00e1ndez S\u00e1nchez\u00a0<\/div>\n<div>17.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Sebasti\u00e1n Galindo Zitle\u00a0<\/div>\n<div>18.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Juan Carlos L\u00f3pez P\u00e9rez\u00a0<\/div>\n<div>19.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Germ\u00e1n Flores Gonz\u00e1lez\u00a0<\/div>\n<div>20.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Andr\u00e9s Fern\u00e1ndez Cortez\u00a0<\/div>\n<div>21.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Manuel Culleo Corona\u00a0<\/div>\n<div>22.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Bonfilio Romero Garc\u00eda\u00a0<\/div>\n<div>23.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Ramiro Garc\u00eda Garc\u00eda\u00a0<\/div>\n<div>24.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Nieves Carrera Jim\u00e9nez\u00a0<\/div>\n<div>25.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Gabriel Rosario Mart\u00ednez\u00a0<\/div>\n<div>26.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Mauricio Gamboa Gonz\u00e1lez\u00a0<\/div>\n<div>27.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Ignacio Rojas Moreno\u00a0<\/div>\n<div>28.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Alberto Valerdi Ram\u00edrez\u00a0<\/div>\n<div>29.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Alejandro Hern\u00e1ndez Y\u00e1\u00f1ez\u00a0<\/div>\n<div>30.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Jes\u00fas Bautista P\u00e9rez\u00a0<\/div>\n<div>31.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Juan Carlos Vidal Garc\u00eda\u00a0<\/div>\n<div>32.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Adri\u00e1n Rojano Rosas\u00a0<\/div>\n<div>33.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Pedro Castillo Torres\u00a0<\/div>\n<div>34.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Gabriel Trejo Santiago\u00a0<\/div>\n<div>35.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Flavio Reyes M\u00e9ndez\u00a0<\/div>\n<div>36.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Rodrigo Mart\u00ednez M\u00e9ndez\u00a0<\/div>\n<div>37.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Jorge Campos Arias\u00a0<\/div>\n<div>38.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Gabriel Milla Pachuca\u00a0<\/div>\n<div>39.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Martiniano V\u00e1zquez Zais\u00a0<\/div>\n<div>40.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Gerardo Gonz\u00e1lez Zamorano\u00a0<\/div>\n<div>41.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Ramiro Torres V\u00e1zquez\u00a0<\/div>\n<div><\/div>\n<div>Y a los siguientes vendedores que llegaron en el momento de la diligencia para comercializar 600 gramos de cable de cobre:\u00a0<\/div>\n<div><\/div>\n<div>42.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Javier Guerrero Cabeza\u00a0<\/div>\n<div>43.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Leandro Hern\u00e1ndez Evangelista\u00a0<\/div>\n<div>44.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Marcos Mu\u00f1oz Palacios\u00a0<\/div>\n<div>45.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Carlos Alduc\u00edn Flores\u00a0<\/div>\n<div>46.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Sa\u00fal Casar\u00edn D\u00edaz\u00a0<\/div>\n<div>\u00a0<\/div>\n<div>Adem\u00e1s, en un inmueble ubicado en la calle Siete Oriente de la colonia El Arenal, en la poblaci\u00f3n de Chachapa, perteneciente al municipio de Amozoc de Mota, con la raz\u00f3n social &#8220;Recuperadora de Metales y Ferrosos M\u00e1rquez&#8221;, se aseguraron:\u00a0<\/div>\n<div><\/div>\n<div>Tres kilos 200 gramos de cable de cobre\u00a0<\/div>\n<div>Dos camionetas\u00a0<\/div>\n<div>Un trascabo\u00a0<\/div>\n<div>Una m\u00e1quina para prensar metal\u00a0<\/div>\n<div><\/div>\n<div>Y se detuvo a los propietarios del lugar:\u00a0<\/div>\n<div><\/div>\n<div>47.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Alfredo M\u00e1rquez Garc\u00eda\u00a0<\/div>\n<div>48.<span style=\"white-space: pre\" class=\"Apple-tab-span\"> <\/span>Francisco Javier M\u00e1rquez Garc\u00eda\u00a0<\/div>\n<div><\/div>\n<div>Derivado de lo anterior, el Fiscal Federal ejercit\u00f3 acci\u00f3n penal contra los detenidos y los puso a disposici\u00f3n del Juez Federal en turno en el interior del Centro de Reinserci\u00f3n Social del estado, quien resolver\u00e1 su situaci\u00f3n jur\u00eddica; dejando a su disposici\u00f3n los inmuebles, el material de cable de cobre, los cartuchos y veh\u00edculos asegurados.\u00a0<\/div>\n<div><\/div>\n<div>El Gobierno Federal sigue trabajando para propiciar un ambiente de certidumbre jur\u00eddica en el que las personas tengan la seguridad de que cuentan con instituciones y programas gubernamentales que garantizan el respeto a sus derechos y la preservaci\u00f3n de su patrimonio mediante la aplicaci\u00f3n de la ley.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Elementos de la AFI detuvieron a 48 personas acusadas de robar cables de Telmex que fueron ubicadas en la privada Hidalgo de la colonia Francisco I. Madero, en el municipio de Puebla, j en la empresa denominada Comercializadora de Metales Angel\u00f3polis S.A. de C.V. \u00a0 Elementos de la AFI detuvieron a 48 personas acusadas de [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":422684,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390481"}],"version-history":[{"count":1,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390481\/revisions"}],"predecessor-version":[{"id":428790,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390481\/revisions\/428790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media\/422684"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}