{"id":390494,"date":"2011-03-17T05:39:21","date_gmt":"2011-03-17T05:39:21","guid":{"rendered":"legacy-k2-2009-10556"},"modified":"2011-03-17T05:39:21","modified_gmt":"2011-03-17T05:39:21","slug":"moreno-valle-no-busca-nuevo-endeudamiento-finanzas-k2-10556","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/moreno-valle-no-busca-nuevo-endeudamiento-finanzas-k2-10556\/390494\/","title":{"rendered":"Moreno Valle no busca nuevo endeudamiento: Finanzas"},"content":{"rendered":"<div>El secretario de Finanzas, Roberto Moya Clemente, reiter\u00f3 que la iniciativa enviada al congreso local de Puebla para que los municipios accedan a cr\u00e9ditos con BANOBRAS, no se trata de un nuevo pr\u00e9stamo buscado por el gobierno estatal, ya que tiene la de 2 mil 500 millones de pesos a\u00fan sin usar<\/div>\n<div>El secretario de Finanzas, Roberto Moya Clemente, volvi\u00f3 aclarar que la iniciativa enviada al congreso local de Puebla para que los municipios accedan a cr\u00e9ditos con BANOBRAS, no se trata de un nuevo pr\u00e9stamo buscado por el gobierno estatal, ya que tiene la de 2 mil 500 millones de pesos.<\/div>\n<div><\/div>\n<div>De manera breve, refiri\u00f3 que el endeudamiento aprobado por los diputados locales pasados fue el techo financiero necesario para la administraci\u00f3n estatal entrante que, en consecuencia no busca m\u00e1s dinero a trav\u00e9s de dicho esquema.<\/div>\n<div><\/div>\n<div>\u201cTenemos una l\u00ednea de cr\u00e9dito y no se requiere adicional\u201d con lo cual dio por terminada la entrevista, tras dar una explicaci\u00f3n de su propuesta que comenz\u00f3 a gestionar con los legisladores en funciones para apoyar a los municipios, misma que consiste en anticipar el 25 por ciento de los recursos anuales que reciben de los fondos de \u00a0Aportaciones para la Infraestructura Socia (FAIS) y el de Aportaciones para el Fortalecimientos de las Entidades Federativas (FAFEF).<\/div>\n<div><\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El secretario de Finanzas, Roberto Moya Clemente, reiter\u00f3 que la iniciativa enviada al congreso local de Puebla para que los municipios accedan a cr\u00e9ditos con BANOBRAS, no se trata de un nuevo pr\u00e9stamo buscado por el gobierno estatal, ya que tiene la de 2 mil 500 millones de pesos a\u00fan sin usar El secretario de [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390494","post","type-post","status-publish","format-standard","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390494"}],"version-history":[{"count":0,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390494\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}