{"id":390503,"date":"2011-03-17T13:40:38","date_gmt":"2011-03-17T13:40:38","guid":{"rendered":"http:\/\/legacy-k2-2009-10565"},"modified":"2026-03-27T18:04:40","modified_gmt":"2026-03-28T00:04:40","slug":"pilar-bernal-recibio-homenaje-postumo-de-la-ampep-k2-10565","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/pilar-bernal-recibio-homenaje-postumo-de-la-ampep-k2-10565\/390503\/","title":{"rendered":"Pilar Bernal recibi\u00f3 homenaje p\u00f3stumo de la AMPEP"},"content":{"rendered":"<p>El cari\u00f1o de quienes recordamos a nuestra entra\u00f1able compa\u00f1era Pilar Bernal, reportera por siempre de Azteca Puebla, hizo eco en el sal\u00f3n paraninfo de la BUAP, el de los eventos importantes, donde entre l\u00e1grimas y aplausos, Pily fue recordada.<\/p>\n<p>A cinco meses de su partida de este mundo y en el marco de la toma de protesta de la nueva mesa directiva de la Asociaci\u00f3n de Mujeres Periodistas presidida por Virginia Castillo Palma, la AMPEP le rindi\u00f3 un homenaje p\u00f3stumo a una gran mujer y periodista, que m\u00e1s de una vez recorri\u00f3 los pasillos de ese lugar, en donde su esencia quedo plasmada.<\/p>\n<p>La nueva Presidenta de la AMPEP, Virginia Castillo Palma, comento que la asociaci\u00f3n ha sido testigo de muchos cambios de la ciudad, \u201dno solo hemos sido testigos sino que hemos comunicado a la sociedad, de la transformaci\u00f3n que ha tenido puebla, desde la cr\u00edtica, \u00e9tica y la investigaci\u00f3n\u201d.<\/p>\n<p>En el evento las integrantes de la asociaci\u00f3n leyeron una semblanza de Pilar Bernal, \u201cfue parte del equipo fundador de la televisora local de TV Azteca Puebla, donde permaneci\u00f3 m\u00e1s de 12 a\u00f1os\u201d (&#8230;) \u201cpero su af\u00e1n por estar justo en el momento en el que ocurr\u00eda la noticia, la hizo que en TV Azteca se convirtiera en una de las reporteras m\u00e1s queridas por la gente, sabia escuchar, observar y plasmar sentimientos\u201d.<\/p>\n<p>Y c\u00f3mo no recordar a una gran mujer periodista, que con cada palabra le imprim\u00eda pasi\u00f3n y amor a su trabajo, una mujer que aceptaba los retos como una prueba y que siempre daba lo mejor en sus reportajes, alguien que con su dulce voz envolv\u00eda a la audiencia, mostrando las realidades, bellezas, alegr\u00edas o tristezas que existen en Puebla.<\/p>\n<p>Para su parte la mam\u00e1 de nuestra amiga y compa\u00f1era, Maria de la Luz D\u00edaz Rosales con voz entre cortada y una profunda nostalgia record\u00f3 su hija \u201cera una persona muy disciplinada, nunca se conformo y siempre quiso dar m\u00e1s de lo que le solicitaban y siempre quer\u00eda ayudar\u201d<\/p>\n<p>Por su parte Hilda Luisa Valdemar, una de las fundadoras de la AMPEP, tambi\u00e9n la record\u00f3, \u201csiento una gran nostalgia por la ausencia, pero por otra parte recordar que ella se hizo acreedora al premio nacional de periodismo que le otorg\u00f3 la federaci\u00f3n de periodismo, y bueno desde aqu\u00ed un abrazo, pero su trabajo seguir\u00e1 fructificando\u201d .<\/p>\n<p>Otra de las periodistas m\u00e1s destacadas de Puebla, compa\u00f1era y amiga de Pily es Olivia P\u00e9rez, quien record\u00f3 los primeros pasos del periodismo a lado de Pily, \u201cyo la conoc\u00ed desde hace mucho tiempo ya mejor no te digo, ella ten\u00eda un programa y yo otro, ella sal\u00eda de la cabina de radio y yo de otra luego nos fuimos a otras empresas y el recuerdo que guardo es de una mujer muy trabajadora, ella hacia diferentes trabajos, desde del medio ambiente hasta investigaciones, trabajos que seguir\u00e1n siendo vistos por otras personas\u201d .<\/p>\n<p>Y para la periodista Pilar Bravo fue m\u00e1s que una reportera, fue una maestra que dej\u00f3 huella, \u201cfue una gran compa\u00f1era con extraordinaria sensibilidad para la cr\u00f3nica e historias de vida\u201d.<\/p>\n<p>Pily dejo un vac\u00edo entre nosotros, pero tambi\u00e9n un legado a las nuevas generaciones de periodistas, que a decir de las mujeres en este \u00e1mbito, seguir\u00e1 contando historias donde quiera que est\u00e9.<\/p>\n<p>&#160;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cari\u00f1o de quienes recordamos a nuestra entra\u00f1able compa\u00f1era Pilar Bernal, reportera por siempre de Azteca Puebla, hizo eco en el sal\u00f3n paraninfo de la BUAP, el de los eventos importantes, donde entre l\u00e1grimas y aplausos, Pily fue recordada. A cinco meses de su partida de este mundo y en el marco de la toma [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390503","post","type-post","status-publish","format-standard","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390503"}],"version-history":[{"count":1,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390503\/revisions"}],"predecessor-version":[{"id":428808,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390503\/revisions\/428808"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}