{"id":390507,"date":"2011-03-17T13:57:19","date_gmt":"2011-03-17T13:57:19","guid":{"rendered":"legacy-k2-2009-10569"},"modified":"2011-03-17T13:57:19","modified_gmt":"2011-03-17T13:57:19","slug":"twitter-fallas-en-servicio-afectaron-a-millones-de-usuarios-k2-10569","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/twitter-fallas-en-servicio-afectaron-a-millones-de-usuarios-k2-10569\/390507\/","title":{"rendered":"Twitter, fallas en servicio afectaron a millones de usuarios"},"content":{"rendered":"<p>Algunos usuarios del sitio de microblogging Twitter identificaron que alrededor del mediod\u00eda de ayer la red social present\u00f3 algunas fallas en su servicio, que afect\u00f3 a gran parte de los casi 200 millones de usuarios que existen en el mundo, seg\u00fan la firma.<\/p>\n<p>La falla no s\u00f3lo perjudic\u00f3 por un par de horas al sitio oficial Twitter.com, sino tambi\u00e9n algunas de las aplicaciones populares para tel\u00e9fonos, tabletas y equipos de c\u00f3mputo como Tweetdeck, Hootsuite, Echofon y otras.<\/p>\n<p>Los usuarios de los servicios de Twitter tuvieron problemas al acceder a sus cuentas, por lo cual manifestaron su malestar a&#160; trav\u00e9s de diversos medios, entre ellos otras redes sociales.<\/p>\n<p>A trav\u00e9s de su cuenta oficial, Twitter dio a conocer a sus seguidores que algunas personas estaban teniendo errores en la p\u00e1gina, ante lo cual se encontraban investigando acerca del problema.<\/p>\n<p>En M\u00e9xico se estima que existen alrededor de 2.5 millones de cuentas de Twitter activas, de las cuales 60 por ciento se ubican en el Distrito Federal.<\/p>\n<p>Este error se da un d\u00eda despu\u00e9s de que la firma diera a conocer en su blog oficial que realizaron un ajuste en cuanto&#160; a la seguridad de las cuentas al agregar el protocolo HTTPS de forma constante.<\/p>\n<p>La compa\u00f1\u00eda no dio a conocer los detalles de la falla en su servicio. Sin embargo, notific\u00f3 que gran parte de las cuentas se hab\u00edan restablecido.<\/p>\n<p>Inform\u00f3 que hace unos d\u00edas se enviaban alrededor de 177 millones de tweets al mes, cifra que va en aumento, por lo cual, por cada minuto que el servicio se detiene, se dejan de enviar m\u00e1s de 120 mil tweets en el mundo.<\/p>\n<p>\u00c9sta es la primera vez en el a\u00f1o que el sitio registra problemas. Sin embargo, el a\u00f1o pasado al realizar una actualizaci\u00f3n en la interfaz de la p\u00e1gina tambi\u00e9n se reportaron fallas, aunque cada vez el impacto es mayor, ya que se estima que diariamente se crean alrededor de 460 mil nuevas cuentas.<br \/>\n&#160;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Algunos usuarios del sitio de microblogging Twitter identificaron que alrededor del mediod\u00eda de ayer la red social present\u00f3 algunas fallas en su servicio, que afect\u00f3 a gran parte de los casi 200 millones de usuarios que existen en el mundo, seg\u00fan la firma. La falla no s\u00f3lo perjudic\u00f3 por un par de horas al sitio [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390507","post","type-post","status-publish","format-standard","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390507"}],"version-history":[{"count":0,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390507\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}