{"id":390516,"date":"2011-03-17T21:18:39","date_gmt":"2011-03-17T21:18:39","guid":{"rendered":"http:\/\/legacy-k2-2009-10580"},"modified":"2026-03-27T18:04:44","modified_gmt":"2026-03-28T00:04:44","slug":"asaltantes-de-caminos-se-apoderaron-de-camion-cargado-con-cajas-de-agua-purificada-k2-10580","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/asaltantes-de-caminos-se-apoderaron-de-camion-cargado-con-cajas-de-agua-purificada-k2-10580\/390516\/","title":{"rendered":"Asaltantes de caminos se apoderaron de cami\u00f3n cargado con cajas de agua purificada"},"content":{"rendered":"<p>Chofer de un cami\u00f3n perteneciente a una empresa de agua purificada fue atracado cuando circulaba por la carretera Ciudad Serd\u00e1n-Tehuac\u00e1n, ya que lo despojaron de la unidad y lo abandonaron en un terreno de cultivo.<\/p>\n<p>El agraviado refiere que ten\u00eda a su cargo la unidad Acasa, t200, modelo 2003, color vino, placas de circulaci\u00f3n 340-EF5, en la cual transportaba cajas de agua purificada, cuando al llegar al kil\u00f3metro 46 de referida vialidad se estacion\u00f3 y fue sorprendido por 3 suetos, quienes con arma de fuego lo despojaron de sus pertenencias y las llaves del cami\u00f3n<\/p>\n<p>Los detractores lo amarraron y lo mantuvieron privado de su libertad por algunas horas hasta que abandonaron al denunciante en un terreno de cultivo ubicado en Tehuac\u00e1n. El hurto qued\u00f3 asentado en la averiguaci\u00f3n AP 279\/2011\/CIUDAD SERD\u00c1N.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chofer de un cami\u00f3n perteneciente a una empresa de agua purificada fue atracado cuando circulaba por la carretera Ciudad Serd\u00e1n-Tehuac\u00e1n, ya que lo despojaron de la unidad y lo abandonaron en un terreno de cultivo. El agraviado refiere que ten\u00eda a su cargo la unidad Acasa, t200, modelo 2003, color vino, placas de circulaci\u00f3n 340-EF5, [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390516","post","type-post","status-publish","format-standard","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390516"}],"version-history":[{"count":1,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390516\/revisions"}],"predecessor-version":[{"id":428822,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390516\/revisions\/428822"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}