{"id":390518,"date":"2011-03-17T23:17:12","date_gmt":"2011-03-17T23:17:12","guid":{"rendered":"legacy-k2-2009-10582"},"modified":"2011-03-17T23:17:12","modified_gmt":"2011-03-17T23:17:12","slug":"familiares-de-detenidos-por-la-afi-acusados-de-robo-a-telmex-denuncian-irregularidades-k2-10582","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/familiares-de-detenidos-por-la-afi-acusados-de-robo-a-telmex-denuncian-irregularidades-k2-10582\/390518\/","title":{"rendered":"Denuncian anomal\u00edas en captura de acusados por robo a Telmex"},"content":{"rendered":"<div>Familiares de los detenidos por la AFI acusados de robar cable a Telmex denunciaron que se trata de personal, incluso de limpieza, que laboraba en Comercializadora de Metales Angel\u00f3polis y que no tienen nada que ver con la operaci\u00f3n del material que ah\u00ed se vende, por lo que solicitaron la informaci\u00f3n del gobernador de Puebla<\/div>\n<div>Familiares de empleados detenidos este lunes de la comercializadora Angel\u00f3polis, acusada por TELMEX por el robo de cableado solicitaron al gobernador Rafael Moreno Valle Rosas su intervenci\u00f3n, pues el s\u00e1bado a m\u00e1s tardar se determinar\u00e1 si los 48 trabajadores son culpables o inocentes, quienes est\u00e1n recluidos en el Cereso de San Miguel.<\/div>\n<div> \u00a0<\/div>\n<div>Este jueves minutos antes de que iniciara el evento de la firma de convenio entre el gobierno estatal y Financiera Rural para otorgar cr\u00e9ditos a productores, alrededor de 20 personas se presentaron afuera del Sal\u00f3n de Protocolos para solicitar la intervenci\u00f3n de las autoridades estatales en este caso que calificaron como una injusticia, pues hasta mujeres que del \u00e1rea de limpieza fueron encarceladas.<\/div>\n<div> \u00a0<\/div>\n<div>Jos\u00e9 Carlos Luna, refiri\u00f3 que su mujer tiene 8 meses como empleada del aseo en esta empresa, y que pese a ello los elementos de la Agencia Federal de Investigaci\u00f3n tambi\u00e9n se la llevaron y quieren responsabilizarla de vender cable propiedad de Tel\u00e9fonos de M\u00e9xico (TELMEX).<\/div>\n<div> \u00a0<\/div>\n<div>Explic\u00f3 que ella y los dem\u00e1s trabajadores, incluidos el gerente y contador de la comercializadora, fueron llevados primero a la delegaci\u00f3n de la Procuradur\u00eda General de la Rep\u00fablica (PGR), ubicada en la Recta a Cholula, para que declararan en este caso y con la promesa de liberarlos, sin embargo ello no se cumpli\u00f3 y los remitieron al penal de San Miguel en calidad de indiciados.<\/div>\n<div> \u00a0<\/div>\n<div>El mismo caso ocurri\u00f3 con el hijo, sobrino y yerno de Manuela M\u00e9ndez, quienes apenas ten\u00edan a\u00f1o y medio, seis y dos meses, respectivamente, trabajando en la empresa ubicada en la colonia Madero, que compra y vende cobre as\u00ed como otro tipo de metales.<\/div>\n<div> \u00a0<\/div>\n<div>Las personas temen que vayan a ser consignados sus familiares por un delito inexistentes, pues ellos no investigan si el material que les llega es robado.<\/div>\n<div> \u00a0<\/div>\n<div> \u00a0<\/div>\n<div> \u00a0<\/div>\n<div> \u00a0<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Familiares de los detenidos por la AFI acusados de robar cable a Telmex denunciaron que se trata de personal, incluso de limpieza, que laboraba en Comercializadora de Metales Angel\u00f3polis y que no tienen nada que ver con la operaci\u00f3n del material que ah\u00ed se vende, por lo que solicitaron la informaci\u00f3n del gobernador de Puebla [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":422678,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390518","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390518"}],"version-history":[{"count":0,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390518\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media\/422678"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}