{"id":390539,"date":"2011-03-18T02:23:13","date_gmt":"2011-03-18T02:23:13","guid":{"rendered":"legacy-k2-2009-10604"},"modified":"2011-03-18T02:23:13","modified_gmt":"2011-03-18T02:23:13","slug":"y-desde-el-congreso-amores-perros-k2-10604","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/y-desde-el-congreso-amores-perros-k2-10604\/390539\/","title":{"rendered":"Y desde el Congreso, amores perros"},"content":{"rendered":"<div>Acab\u00f3 la ilusi\u00f3n creada por los aliancistas respecto a descubrir y condenar a los malosos ex funcionarios marinistas. Basados en infundios y calumnias sin sustento real, los aliancistas que hicieron su agosto en julio pasado hoy no tienen cara para descalificar m\u00e1s a Mar\u00edn. <\/div>\n<div>\u00a0<\/div>\n<div>Proclives a los chismes \u00a0surgidos del resentimiento t\u00edpico de los que no pasan de ser maceta de corredor y apoy\u00e1ndose \u00a0en el dicho de meretrices y holgazanes- que en su momento dejaron de ser parte de la administraci\u00f3n marinista justamente \u00a0por esas causas- los aliancistas y sus corifeos buscaron denodadamente da\u00f1ar la reputaci\u00f3n de todos los que colaboramos en ese sexenio. <\/div>\n<div>\u00a0<\/div>\n<div>Si bien es cierto hubo quienes se pasaron de listos como funcionarios p\u00fablicos en el marinismo, otros procuramos dar siempre lo mejor en la encomienda p\u00fablica que nos toco. Obviamente, quienes ten\u00edamos una clara identificaci\u00f3n con el \u00a0Lic. Mar\u00edn, sab\u00edamos que \u00edbamos a ser revisados con dolo y mala leche con tal de manchar la buena fama p\u00fablica que muchos forjamos a lo largo de m\u00e1s de muchos a\u00f1os de servicio p\u00fablico. <\/div>\n<div>\u00a0<\/div>\n<div>Tremenda rota \u00a0de trompa se han de haber llevado quienes en este deleznable y perverso empe\u00f1o, no lograron su cometido. Por ello parece un exceso protag\u00f3nico de parte del convergente, cuando sale a los medios a utilizar como pretexto de su rompimiento con los aliancistas, la aprobaci\u00f3n de la cuenta p\u00fablica marinista \u00a1Por favor! \u00bfAcaso para darle gusto tendr\u00edan los dem\u00e1s diputados que negarse a aceptar una verdad irrefutable respecto a la cuenta marinista? \u00a1Qu\u00e9 iluso! Preocupado deber\u00eda estar al saber que gente con antecedentes delictivos y m\u00e1s de 2 denuncias en su contra, han asumido cargos a nivel directivo en diferentes Secretar\u00edas y Organismos p\u00fablicos. <\/div>\n<div>\u00a0<\/div>\n<div>Caso concreto el del famoso doctor Juan V\u00e1zquez Rodr\u00edguez- reconocido por sus perversiones sexuales que siempre recalan en enfermeras, secretarias y hasta j\u00f3venes pasantes de medicina que por desgracia se llegaron a topar con \u00e9l. Pese a estos antecedentes \u00a0 el convergente gusta de distraer la atenci\u00f3n de la ciudadan\u00eda victimiz\u00e1ndose como si tuviera realmente \u00a0raz\u00f3n de sus pataletas. <\/div>\n<div>\u00a0<\/div>\n<div>Lo que no ubica es que luego de su cuasi adoraci\u00f3n \u2013 \u00f3 su abyecta disposici\u00f3n- hacia Moreno Valle y sus proyectos, resulta incre\u00edble que ahora se rebele a las indicaciones que su gu\u00eda moral l dicte. Preocupado tambi\u00e9n deber\u00eda estar de que gente que goz\u00f3 de muchas consideraciones y apoyos durante l sexenio marinista, terminaron comport\u00e1ndose como \u00a0rameras de la peor ralea. Hambreados que con tal de no perder sus \u201cchambas\u201d optaron por ayudar a sus nuevos jefes a armar expedientes basados en chismes y versiones que frente a una denuncia penal y otra civil, se caer\u00edan antes de la primera audiencia por falta de elementos. <\/div>\n<div>\u00a0<\/div>\n<div>En esas condiciones\u2026\u00a1menudo rid\u00edculo que iban a hacer! La aprobaci\u00f3n de la \u00faltima \u00a0cuenta p\u00fablica de Mario Mar\u00edn, pas\u00f3 por que las comprobaciones del uso de recursos materiales y econ\u00f3micos en el sexenio pasado, estaban perfectamente \u00a0verificadas y auditadas. Desde luego esto sirvi\u00f3 para demostrar que Mar\u00edn estuvo consciente del riesgo que implica no cuidar el fondo y la forma a la hora de usar y entregar recursos p\u00fablicos durante una encomienda constitucional como la que \u00e9l y los miembros de su gabinete \u00a0tuvieron en sus manos. <\/div>\n<div>\u00a0<\/div>\n<div>De ah\u00ed que los gritos y sombrerazos con los que los aliancistas ilusionaron falsamente a sus seguidores- argumentando que el marinismo fue un sexenio plagado de abusos, corruptelas y arbitrariedades y lo llevar\u00edan \u00a0al cadalso- se quedaron sin argumentos. <\/div>\n<div>\u00a0<\/div>\n<div>Nada de que hubo acuerdo \u00f3 contubernio con Moreno Valle como puerilmente lo declar\u00f3 el convergente \u00bfPara qu\u00e9 se revela? No ha entendido que NO se debe morder la mano de quien te da de comer? Porque le guste o no, fue Rafael Moreno Valle quien lo hizo. Respecto al pri\u00edsta que vot\u00f3 en contra, basta con recordar el profundo resentimiento que le tiene a Mar\u00edn en lo personal. Ergo\u2026solo se desquit\u00f3. <\/div>\n<div>\u00a0<\/div>\n<div>En cuanto a las babadas expresadas por este muchacho Mondrag\u00f3n, la verdad es que solo invita a revirarle\u2026 \u201cpara eso me gustabas mi chavo\u201d. En cuanto a la Buxad\u00e9, ser\u00eda bueno que le quitaran los espejos de su casa, porque luego de su gris y anodino paso por el Congreso, se va a ver m\u00e1s fea y ahajada que su amiga Guadalupe Loaiza. Peor a\u00fan, se va a sentir tan disminuida por haber defraudado la confianza de quienes creyeron que realmente ser\u00eda una revelaci\u00f3n legislativa y se equivocaron \u00a1Con la pena! \u00a0Ya no podr\u00e1 zapatear en la tumba que tanto deseaba su plagiadora y senil suegra. <\/div>\n<div>\u00a0<\/div>\n<div>En suma YA perdi\u00f3 como la mayor\u00eda de los diputados, calidad moral para hacer cr\u00edtica ALGUNA. \u00a0Prefiri\u00f3 no poner en riesgo su jugosa dieta \u00a0antes que sostener su \u00bfcongruencia? ciudadana. Con estas actitudes parlamentarias- incluyendo la del bufoncito millonario del PANAL- es urgente cuidar que \u00a0esquiroles y genuflexos no vuelvan a apoderarse de esca\u00f1os \u00a0legislativos, ya que terminan evidenciados como chivos en cristaler\u00eda \u00f3 macacos en el mejor de los casos. <\/div>\n<div>\u00a0<\/div>\n<div>El problema \u00a0que inevitablemente \u00a0afrontar\u00e1 \u00a0este sexenio aliancista, es que est\u00e1 plagado de seudo pol\u00edticos bocones y perniciosos; de ociosos y desleales. De borregos y mercenarios. Muy contados los personajes valiosos y comprometidos- Patricia Leal, Marcelo Almaguer, Tony Gali, Bernardo Huerta, Eduardo Tobilla, Mercede Aguilar y hasta Aguilar Chedraui. <\/div>\n<div>\u00a0<\/div>\n<div>La mayor\u00eda est\u00e1n del nabo como el pat\u00e9tico \u00a0homo f\u00f3bico de Aldo Cruz P\u00e9rez \u00a1Pobre Rafael! Los aliancistas presumen de ser una opci\u00f3n decente y moral \u00bfCu\u00e1l? El d\u00eda que se deshagan de los nefastos desleales, porros, corruptos y haraganes que tanto da\u00f1aron \u00a0a los sexenios pri\u00edstas- ahora reciclad\u00edsimos por Moreno Valle v\u00eda Melquiades Morales, a TODOS nos cantar\u00e1 otro gallo. Mientras tanto y ya que el convergente \u00a0quiere presumir de congruente, que siga haciendo se\u00f1alamientos porque solo han pasado 47 d\u00edas de su anhelado sexenio \u00a1Salud!\u00a0<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Acab\u00f3 la ilusi\u00f3n creada por los aliancistas respecto a descubrir y condenar a los malosos ex funcionarios marinistas. Basados en infundios y calumnias sin sustento real, los aliancistas que hicieron su agosto en julio pasado hoy no tienen cara para descalificar m\u00e1s a Mar\u00edn. \u00a0 Proclives a los chismes \u00a0surgidos del resentimiento t\u00edpico de los [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":422667,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390539","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390539"}],"version-history":[{"count":0,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390539\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media\/422667"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}