{"id":390551,"date":"2011-03-18T13:39:24","date_gmt":"2011-03-18T13:39:24","guid":{"rendered":"http:\/\/legacy-k2-2009-10616"},"modified":"2026-03-27T18:05:34","modified_gmt":"2026-03-28T00:05:34","slug":"marin-gasto-2509-millones-de-pesos-diarios-en-su-ultimo-mes-de-gobierno-k2-10616","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/marin-gasto-2509-millones-de-pesos-diarios-en-su-ultimo-mes-de-gobierno-k2-10616\/390551\/","title":{"rendered":"Mar\u00edn gast\u00f3 250.9 millones de pesos diarios en su \u00faltimo mes de gobierno"},"content":{"rendered":"<p>Entre el 1 y el 31 de enero, \u00faltimo mes de la administraci\u00f3n del ex gobernador Mario Mar\u00edn Torres, el gobierno estatal gast\u00f3 68 por ciento m\u00e1s de recursos que lo que erog\u00f3 diariamente durante todo el 2010, seg\u00fan se aprecia en un comparativo de los estados financieros de ambos periodos avalados por el Congreso local.<\/p>\n<p>Durante el pasado mes de enero, Mar\u00edn ejerci\u00f3 7 mil millones 779 mil pesos, que divididos entre los 31 d\u00edas de ese periodo, dan como resultado un gasto diario de 250.9 millones de pesos.<\/p>\n<p>Sin embargo, durante el 2010 el ex mandatario erog\u00f3 recursos por 54 mil 196 millones, que divididos entre los 365 d\u00edas que conforman ese a\u00f1o, resultan en un gasto diario de 148.4 millones de pesos.<\/p>\n<p>Es decir, cada d\u00eda del \u00faltimo mes su sexenio Mario Mar\u00edn gast\u00f3 102.5 millones de pesos m\u00e1s que lo que ejerci\u00f3 diariamente durante todo un a\u00f1o.<\/p>\n<p>Pese a la diferencia en los montos, los diputados de la extinta coalici\u00f3n Compromiso por Puebla \u2013que fueron oposici\u00f3n durante el pasado proceso electoral\u2013 avalaron la cuenta p\u00fablica del ex mandatario, correspondiente al mes de enero de 2011, a excepci\u00f3n de los legisladores Jos\u00e9 Juan Espinosa Torres (Convergencia) y Julio Lorenzini Rangel (PAN).<\/p>\n<p>Al justificar el sentido del voto de la mayor\u00eda de los integrantes de su bancada, el coordinador de los diputados del PAN, Mario Riestra Pi\u00f1a, justific\u00f3 que aprobaron la cuenta porque s\u00f3lo representa el 1.3 por ciento de los recursos que Mar\u00edn ejerci\u00f3 en todo su sexenio.<\/p>\n<p>\u201cEstamos avalando el \u00faltimo un mes de los 72 que conformaron la administraci\u00f3n de Mario Mar\u00edn\u201d, argument\u00f3 Riestra.<\/p>\n<p>Sin embargo el comparativo diario evidencia la magnitud del gasto gubernamental.<\/p>\n<p>Del total de recursos aplicados por el antecesor de Rafael Moreno Valle en el \u00faltimo mes de su gesti\u00f3n, el gasto m\u00e1s fuerte se realiz\u00f3 en el pago de servicios personales (n\u00f3mina), pues se erogaron 1 mil 953 millones de pesos.<\/p>\n<p>Para educaci\u00f3n se gastaron 1 mil 642 millones de pesos, sin embargo la mayor parte de esos recursos se destinaron al pago de los salarios de los docentes.<\/p>\n<p>Finalmente, 1 mil 263 millones se destinaron al rubro de transferencias, asignaciones, subsidios y otras ayudas.<\/p>\n<p>&#160;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre el 1 y el 31 de enero, \u00faltimo mes de la administraci\u00f3n del ex gobernador Mario Mar\u00edn Torres, el gobierno estatal gast\u00f3 68 por ciento m\u00e1s de recursos que lo que erog\u00f3 diariamente durante todo el 2010, seg\u00fan se aprecia en un comparativo de los estados financieros de ambos periodos avalados por el Congreso [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390551","post","type-post","status-publish","format-standard","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390551"}],"version-history":[{"count":1,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390551\/revisions"}],"predecessor-version":[{"id":428848,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390551\/revisions\/428848"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}