{"id":390559,"date":"2011-03-18T14:24:44","date_gmt":"2011-03-18T14:24:44","guid":{"rendered":"http:\/\/legacy-k2-2009-10626"},"modified":"2026-03-27T18:05:37","modified_gmt":"2026-03-28T00:05:37","slug":"hector-ortiz-ex-gobernador-de-tlaxcala-denunciado-ante-pgr-por-despojo-k2-10626","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/hector-ortiz-ex-gobernador-de-tlaxcala-denunciado-ante-pgr-por-despojo-k2-10626\/390559\/","title":{"rendered":"H\u00e9ctor Ortiz, ex gobernador de Tlaxcala, denunciado ante PGR por despojo"},"content":{"rendered":"<p>El ex Gobernador de Tlaxcala, el panista H\u00e9ctor Ortiz Ortiz, enfrenta una denuncia ante la Procuradur\u00eda General de la Rep\u00fablica (PGR) por presunto despojo de un predio de 40 mil metros cuadrados en el Municipio de Tlaxco, donde se ubica una zona arqueol\u00f3gica.<\/p>\n<p>Se trata del \u00e1rea conocida como Los Laberintos, al norte del Estado, la cual est\u00e1 registrada ante el Instituto Nacional de Antropolog\u00eda e Historia (INAH).<\/p>\n<p>De acuerdo con la querella AP\/PGR\/5126\/2011, de la cual REFORMA posee copia, desde 2008 el predio fue rodeado presuntamente por \u00f3rdenes de Ortiz Ortiz para fincar un rancho de su propiedad denominado Tectipa o Tectipan.<\/p>\n<p>Tras considerar que se perjudic\u00f3 el patrimonio municipal y un bien nacional con las acciones del ex Mandatario y para exigir el rescate del predio, Iluzka Mejorada Palacios, vecina del Municipio de Tlaxco y presidenta de una ONG de nombre Madres Solteras, promovi\u00f3 la denuncia por el delito de despojo en contra del ex Mandatario y quienes resulten responsables.<\/p>\n<p>La querella fue interpuesta ante la Procuradur\u00eda el 14 de enero, un d\u00eda antes de que Ortiz Ortiz entregara la Gubernatura al priista Mariano Gonz\u00e1lez.<\/p>\n<p>En el documento, la denunciante argumenta que, derivado de una investigaci\u00f3n en el INAH y la Comisi\u00f3n Nacional del Agua (Conagua), se determin\u00f3 que el predio de Los Laberintos es propiedad de la Naci\u00f3n.<\/p>\n<p>Incluso, desde 1980, el lugar posee un registro ante el INAH con n\u00famero E142329064 y se le denomina Tlaxco de Morelos.<\/p>\n<p>Tambi\u00e9n existe una queja con n\u00famero 11\/010\/DRQ\/0733\/2008 ante el \u00d3rgano Interno de Control del INAH por da\u00f1o e invasi\u00f3n de esa superficie ante el intento de convertirla en propiedad privada.<\/p>\n<p>Seg\u00fan las pruebas que present\u00f3 Mejorada Palacios para sustentar su denuncia, la Conagua tambi\u00e9n considera el predio como una zona federal, ya que cuenta con algunos veneros que abastecen de agua al r\u00edo Zahuapan.<\/p>\n<p>De acuerdo con los expedientes del INAH, el predio de Los Laberintos abarca una superficie de 40 mil metros cuadrados y actualmente presenta alteraciones por obras de remoci\u00f3n y movimiento de tierras.<\/p>\n<p>Vecinos de Tlaxco explicaron a REFORMA que el despojo de Los Laberintos inici\u00f3 en 2007, cuando, a trav\u00e9s de un juicio, una persona intent\u00f3 apropiarse de un rancho abandonado en el lugar.<\/p>\n<p>Pobladores del lugar aseguran que el asunto lleg\u00f3 a o\u00eddos del ex Gobernador, quien, para evitarlo, hizo los tr\u00e1mites correspondientes para que la propiedad pasara a ser un bien de la Naci\u00f3n.<\/p>\n<p>&#8220;Entonces, hizo los tr\u00e1mites para que fuera de bienes nacionales, pero no fue para bienes nacionales; m\u00e1s bien, fue para \u00e9l&#8221;, dijo \u00c1ngel Guevara.<\/p>\n<p>El hombre, de 67 a\u00f1os de edad, narr\u00f3 que el predio de Los Laberintos sirvi\u00f3 de escenario para varias pel\u00edculas, entre ellas &#8220;El hijo de Juan charrasqueado&#8221;, de la cual fue extra con un papel de caballerango.<\/p>\n<p>El lugar, abund\u00f3, era para las familias un lugar de visita o d\u00eda de campo.<\/p>\n<p>Sin embargo, actualmente el sitio est\u00e1 cercado y forma parte de un rancho propiedad de Ortiz Ortiz y sus hermanos.<\/p>\n<p>&#8220;La gente viene, pero ya no como antes (&#8230;) Los Laberintos son muy grandes, pero los meros, meros, est\u00e1n encerrados en los terrenos del rancho&#8221;, acot\u00f3.<\/p>\n<p><strong>Evaden despojo de Los Laberintos<\/strong><\/p>\n<p>A la Secretar\u00eda de Turismo del Estado (Secture) no le preocupa el supuesto despojo de Los Laberintos de Tlaxco, porque no es funci\u00f3n de esta dependencia defender los atractivos tur\u00edsticos con problemas legales.<\/p>\n<p>As\u00ed lo manifest\u00f3 el titular de esa dependencia, Marco Antonio Mena Rodr\u00edguez, al ser cuestionado sobre la denuncia contra el ex Gobernador panista H\u00e9ctor Ortiz por supuestamente haberse adue\u00f1ado de un \u00e1rea considerada por el INAH como zona arqueol\u00f3gica, y donde finc\u00f3 un rancho familiar.<\/p>\n<p>El funcionario aludi\u00f3 que las funciones de la Secture son difundir y promover el turismo en el estado, no resolver asuntos legales relacionados con los destinos locales.<\/p>\n<p>&#8220;La Secretar\u00eda de Turismo tiene establecido muy claro cu\u00e1les son sus funciones; cumple con sus funciones y no est\u00e1n referidas al tema (del presunto despojo)&#8221;, arguy\u00f3.<\/p>\n<p>Para resolver ese tipo de asuntos, se\u00f1al\u00f3, est\u00e1 la Secretar\u00eda de la Funci\u00f3n P\u00fablica del Estado o el \u00d3rgano de Fiscalizaci\u00f3n Superior.<\/p>\n<p>Incluso, expuso que si alguno de los destinos tur\u00edsticos de la entidad enfrenta alguna querella, no representa un problema, ya que la Secture s\u00f3lo concentra su trabajo en el eje tur\u00edstico &#8220;Tlaxcala, ciudad Tlaxcala y Huamantla&#8221;.<\/p>\n<p>&#8220;El hecho de que uno de los atractivos tenga un proceso legal, no significa que la oferta tur\u00edstica del estado se afecte&#8221;, dijo.<\/p>\n<p>Desde 2008, la Secretar\u00eda de Turismo del Estado dej\u00f3 de difundir a Los Laberintos como atractivo tur\u00edstico de la entidad.<\/p>\n<p>El \u00e1rea era promovida como un conjunto de formaciones rocosas y cavernosas.<\/p>\n<p>\n&#160;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ex Gobernador de Tlaxcala, el panista H\u00e9ctor Ortiz Ortiz, enfrenta una denuncia ante la Procuradur\u00eda General de la Rep\u00fablica (PGR) por presunto despojo de un predio de 40 mil metros cuadrados en el Municipio de Tlaxco, donde se ubica una zona arqueol\u00f3gica. Se trata del \u00e1rea conocida como Los Laberintos, al norte del Estado, [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390559","post","type-post","status-publish","format-standard","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390559"}],"version-history":[{"count":1,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390559\/revisions"}],"predecessor-version":[{"id":428856,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390559\/revisions\/428856"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}