{"id":390584,"date":"2011-03-19T00:54:38","date_gmt":"2011-03-19T00:54:38","guid":{"rendered":"http:\/\/legacy-k2-2009-10651"},"modified":"2026-03-27T18:06:19","modified_gmt":"2026-03-28T00:06:19","slug":"pri-acepta-a-medias-evaluacion-de-diputados-por-el-centro-espinosa-yglesias-k2-10651","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/pri-acepta-a-medias-evaluacion-de-diputados-por-el-centro-espinosa-yglesias-k2-10651\/390584\/","title":{"rendered":"PRI acepta a medias evaluaci\u00f3n de diputados por el Centro Espinosa Yglesias"},"content":{"rendered":"<div>La fracci\u00f3n parlamentaria del Partido PRI no ten\u00eda conocimiento de que el Centro de Estudios Espinosa Yglesias fuera a hacer una evaluaci\u00f3n del trabajo del Poder Legislativo y de quienes lo conforman, asegur\u00f3 el l\u00edder de la bancada, Jos\u00e9 Luis M\u00e1rquez Mart\u00ednez, quien agreg\u00f3 que la mejor opini\u00f3n es la de los ciudadanos<\/div>\n<div>La fracci\u00f3n parlamentaria del Partido Revolucionario Institucional (PRI) no ten\u00eda conocimiento de que el Centro de Estudios Espinosa Yglesias (CEEY) fuera hacer una evaluaci\u00f3n del trabajo del Poder Legislativo y de quienes lo conforman, asegur\u00f3 el diputado Jos\u00e9 Luis M\u00e1rquez Mart\u00ednez.<\/div>\n<div>\u00a0<\/div>\n<div>Subray\u00f3 que la principal evaluaci\u00f3n es la de los ciudadanos, ya que es el mejor observador y cr\u00edtico, en donde es quien vuelve a dar o castigar con su voto, de ah\u00ed quien toma la determinaci\u00f3n de la mejor alternativa en las campa\u00f1as.<\/div>\n<div>\u00a0<\/div>\n<div>\u201cEsto es lo que m\u00e1s nos interesa, no nos oponemos y bienvenido, s\u00f3lo que se desconoc\u00eda cu\u00e1l era su intenci\u00f3n y metodolog\u00eda, adem\u00e1s de que no abarca el trabajo de un legislador\u201d, acot\u00f3.<\/div>\n<div>\u00a0<\/div>\n<div>M\u00e1rquez Mart\u00ednez puntualiz\u00f3, que s\u00f3lo ser\u00e1 un documento valioso que analizaremos y observaremos, pero lo m\u00e1s importante es lo que los ciudadanos opinen y digan la sociedad.<\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La fracci\u00f3n parlamentaria del Partido PRI no ten\u00eda conocimiento de que el Centro de Estudios Espinosa Yglesias fuera a hacer una evaluaci\u00f3n del trabajo del Poder Legislativo y de quienes lo conforman, asegur\u00f3 el l\u00edder de la bancada, Jos\u00e9 Luis M\u00e1rquez Mart\u00ednez, quien agreg\u00f3 que la mejor opini\u00f3n es la de los ciudadanos La fracci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390584","post","type-post","status-publish","format-standard","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390584"}],"version-history":[{"count":1,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390584\/revisions"}],"predecessor-version":[{"id":428878,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390584\/revisions\/428878"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}