{"id":390592,"date":"2011-03-21T03:05:18","date_gmt":"2011-03-21T03:05:18","guid":{"rendered":"legacy-k2-2009-10659"},"modified":"2011-03-21T03:05:18","modified_gmt":"2011-03-21T03:05:18","slug":"pericos-inicia-temporada-con-victoria-ante-sultanes-k2-10659","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/pericos-inicia-temporada-con-victoria-ante-sultanes-k2-10659\/390592\/","title":{"rendered":"Pericos y su madrina Marisol Gonz\u00e1lez"},"content":{"rendered":"<div>\nEste s\u00e1bado&#160;Los Pericos debutaron&#160;en la campa\u00f1a 2011 de la Liga Mexicana de Beisbol (LMB) con un triunfo por 8-7 en 10 largas entradas, sobre Sultanes de Monterrey, ante un repleto Estadio Hermanos Serd\u00e1n y la presencia de la madrina Marisol Gonz\u00e1lez<\/div>\n<div>&#160;<\/div>\n<div><\/div>\n<div>&#160;<\/div>\n<div>El sitio en internet f\u00f3rmula noticias informa que Pericos de Puebla debut\u00f3 la noche del s\u00e1bado en la campa\u00f1a 2011 de la Liga Mexicana de Beisbol (LMB) con un triunfo por 8-7 en 10 largas entradas, sobre Sultanes de Monterrey, ante un repleto Estadio Hermanos Serd\u00e1n.<\/div>\n<div>&#160;<\/div>\n<div>Pericos, monarca de la Zona Sur y subcampe\u00f3n LMB en el 2010, asegur\u00f3 el triunfo en esa d\u00e9cima entrada, luego que Omar de la Torre remolc\u00f3 la carrera del triunfo con una l\u00ednea de sacrificio.<\/div>\n<div>\n&#160;<\/div>\n<div>La victoria fue para Jos\u00e9 Avalos, en una buena labor de relevo, mientras que la derrota se le apunt\u00f3 a Juan Pablo Menchaca.<\/div>\n<div>\n&#160;<\/div>\n<div>Pericos de Puebla comenz\u00f3 el partido con un potente rally de seis carreras en la primera entrada, el cual fue determinante para conseguir el triunfo.<\/div>\n<div>\n&#160;<\/div>\n<div>La primera raya entr\u00f3 de &#8220;caballito&#8221; con el pasaporte otorgado al dominicano Mendy L\u00f3pez con la casa llena, y despu\u00e9s Ren\u00e9 Reyes y Omar De la Torre impulsaron cada uno par de carreras espalda con espalda, para explotar al abridor Rosman Garc\u00eda.<\/div>\n<div>\n&#160;<\/div>\n<div>Cerr\u00f3 el racimo Seraf\u00edn Rodr\u00edguez, quien peg\u00f3 hit al central para remolcar la sexta anotaci\u00f3n.<\/div>\n<div>\n&#160;<\/div>\n<div>Sultanes reaccion\u00f3 en la segunda entrada con otro rally, \u00e9ste de cinco carreras para poner el 6-5, y posteriormente empat\u00f3 el cotejo en 6-6 en la cuarta tanda, gracias a una rola a la inicial de Kar\u00edm Garc\u00eda.<\/div>\n<div>\n&#160;<\/div>\n<div>Pericos retom\u00f3 la ventaja en el sexto inning con batazo productor al izquierdo de Seraf\u00edn Rodr\u00edguez, pero Sultanes volvi\u00f3 a empatar a 7-7 en el s\u00e9ptimo rollo con carrera de &#8220;caballito&#8221;.<\/div>\n<div>\n&#160;<\/div>\n<div>El duelo se defini\u00f3 en favor de Pericos en el d\u00e9cimo rollo. Con casa llena y sin out, Juan Pablo Menchaca recibi\u00f3 l\u00ednea al derecho de Omar De la Torre, y en pisa y corre el corredor emergente Eliezer Ortiz anot\u00f3 la de la diferencia.<\/div>\n<div>\n&#160;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Este s\u00e1bado&#160;Los Pericos debutaron&#160;en la campa\u00f1a 2011 de la Liga Mexicana de Beisbol (LMB) con un triunfo por 8-7 en 10 largas entradas, sobre Sultanes de Monterrey, ante un repleto Estadio Hermanos Serd\u00e1n y la presencia de la madrina Marisol Gonz\u00e1lez &#160; &#160; El sitio en internet f\u00f3rmula noticias informa que Pericos de Puebla debut\u00f3 [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":422647,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390592","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390592"}],"version-history":[{"count":0,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390592\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media\/422647"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}