{"id":390620,"date":"2011-03-22T00:34:43","date_gmt":"2011-03-22T00:34:43","guid":{"rendered":"legacy-k2-2009-10687"},"modified":"2011-03-22T00:34:43","modified_gmt":"2011-03-22T00:34:43","slug":"el-poder-contra-los-ciudadanos-k2-10687","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/el-poder-contra-los-ciudadanos-k2-10687\/390620\/","title":{"rendered":"El poder contra los ciudadanos"},"content":{"rendered":"<div>El primer per\u00edodo de sesiones del Congreso local, termin\u00f3 con la farsa de la coalici\u00f3n \u201cCompromiso por Puebla\u201d. Las enormes diferencias ideol\u00f3gicas se hicieron patentes, al presentarse la iniciativa para la despenalizaci\u00f3n del aborto y la aceptaci\u00f3n de las sociedades en convivencia. Y para rematar se aprob\u00f3 la \u00faltima cuenta p\u00fablica de Mario Mar\u00edn.<\/div>\n<div>\u00a0<\/div>\n<div>Al calor de estos enfrentamientos el diputado Jos\u00e9 Juan Espinosa Torres, dej\u00f3 al descubierto el acuerdo celebrado entre el ex gobernador y el nuevo mandatario. Espinosa manifest\u00f3 que el secretario de Gobierno, Fernando Manzanilla, fue el encargado de transmitir a los nuevos diputados las instrucciones de que deber\u00edan aprobar la cuenta del ex gobernador; se lo prometieron pensando en garantizar la gobernabilidad.<\/div>\n<div>\u00a0<\/div>\n<div>Los poblanos ya nos hab\u00edamos dado cuenta \u201cdesde endenantes\u201d. Empez\u00f3 la sospecha cuando la anterior legislatura que estaba integrada por una mayor\u00eda priista, de buenas a primeras aprob\u00f3 un cr\u00e9dito de 2500 millones para que los ejerciera el nuevo mandatario, as\u00ed como un paquete de reformas e iniciativas que servir\u00edan para iniciar su gesti\u00f3n.<\/div>\n<div>\u00a0<\/div>\n<div>Siempre ha sido el secretario de Gobernaci\u00f3n el encargado de dictar la l\u00ednea a los diputados poblanos. Y tambi\u00e9n han existido diputados dignos y congruentes que se niegan a acatarla, cuando consideran que se viola la Constituci\u00f3n, las leyes que de ella emanan o la ideolog\u00eda del partido que los llev\u00f3 a ocupar una curul. <\/div>\n<div>\u00a0<\/div>\n<div>Felicidades al diputado Espinosa por el nacimiento de su hijo y por el valor de oponerse a las instrucciones gubernamentales. Desde luego que debe estar preparado para afrontar las consecuencias de su acci\u00f3n. Se le vendr\u00e1n encima los sicarios de la prensa; le mandar\u00e1n auditorias a sus empresas o de sus familiares. Es la costumbre. Lo \u00fanico que no podr\u00e1n limitar es su libertad de expresi\u00f3n en la tribuna ya que lo protege el fuero constitucional.<\/div>\n<div>\u00a0<\/div>\n<div>Los dem\u00e1s mortales que no gozamos de esa protecci\u00f3n, tendremos que cuidarnos de no caerle \u00a0mal a alguno de los nuevos poderosos, porque pueden usar en nuestra contra la anticonstitucional reforma al da\u00f1o moral y ser despojados de nuestro patrimonio: se aument\u00f3 de mil a tres mil los \u00a0salarios m\u00ednimos de sanci\u00f3n al da\u00f1o moral, lo que deja abierto el da\u00f1o patrimonial. Aunque dice Ernesto Villanueva, personaje destacado en el \u00e1mbito jur\u00eddico que la Fundalex puede dedicarse a sacar amparos indirectos para los periodistas que se sientan vulnerables, por la nueva redacci\u00f3n del C\u00f3digo Civil. \u00bfUsted cree que el presidente de la Fundaci\u00f3n de marras, amigo del gobernador, se atrever\u00e1 a pelear por la libertad de expresi\u00f3n en Puebla?<\/div>\n<div>\u00a0<\/div>\n<div>Otro caso en el que hay confusi\u00f3n es en el fundamento para la toma por la fuerza p\u00fablica del \u201cValle Fant\u00e1stico\u201d. Por una parte el gobierno del estado manifest\u00f3 que hab\u00eda recuperado el predio en donde se asienta el parque de diversiones, por una orden del juez de San Pedro Cholula. Incluso la directiva del Ilustre Colegio de abogados en una carta abierta apoyaron la restituci\u00f3n del predio al gobierno del Estado. Pero para que esto suceda, la restituci\u00f3n, debe haber una sentencia definitiva en un juicio en que se haya o\u00eddo y vencido al propietario del terreno, de acuerdo con lo establecido en el art\u00edculo 16 de la Constituci\u00f3n, lo cual debi\u00f3 darse en menos de un mes, desde que se interpuso la demanda el 2 de febrero, hasta que se dict\u00f3 la resoluci\u00f3n del juez.<\/div>\n<div>\u00a0<\/div>\n<div>Por otra parte, el Procurador de Justicia de Puebla declar\u00f3 que lo que se hizo fue una medida cautelar para asegurar el predio, mientras que se realiza el juicio de nulidad de la donaci\u00f3n onerosa, juicio en el cual el demandado podr\u00eda presentar las pruebas que a su derecho convengan y que la sentencia se dictar\u00eda hasta en a\u00f1os, sin saberse cu\u00e1l de las partes tendr\u00e1 la raz\u00f3n jur\u00eddica. Esto es como si a usted le promueven un embargo precautorio y le recogen su autom\u00f3vil, para garantizar que no se deshaga de \u00e9l o para presionarlo a llegar a un acuerdo. \u00bfCu\u00e1l de los dos es la verdad? Habr\u00eda que revisar el expediente. No me cabe duda que el resultado favorecer\u00e1 al gobierno. Despu\u00e9s del documental \u201cPresunto Culpable\u201d, no se necesita mayor explicaci\u00f3n.<\/div>\n<div>\u00a0<\/div>\n<div>Muchos de los predios de la Reserva Atlixcayotl, nombre que por cierto el Procurador no pudo pronunciar, est\u00e1n en condiciones similares, pero no sus propietarios. Seg\u00fan escribe Valent\u00edn Varillas, se enviaron varios emisarios a Henaine para ofrecerle el cambio del Valle por otro terreno de 7 hect\u00e1reas en la misma zona con uso de suelo mixto para desarrollar un proyecto comercial y de vivienda, la compra de sus acciones en el Aeropuerto de Huejotzingo y una opci\u00f3n para la \u00a0venta del equipo de futbol La Franja. Pero chocaron los caracteres de dos triunfadores y Henaine se enfrent\u00f3 al poder. Ahora todos contra \u00e9l, Conciliaci\u00f3n y arbitraje, las procuradur\u00edas y los medios. Recurri\u00f3 a la Comisi\u00f3n de Derechos Humanos de Puebla, y su caso lo atrajo la Comisi\u00f3n Nacional, en donde trabajaba Juan Pablo Pi\u00f1a y lo hace su mam\u00e1. \u00bfQu\u00e9 creen que le depare la recomendaci\u00f3n al consejero jur\u00eddico?<\/div>\n<div>\u00a0<\/div>\n<div>Lo \u00fanico que nos tranquiliza es la declaraci\u00f3n de Manzanilla: dice que se respetar\u00e1n los derechos de todos los que act\u00faen conforme a la ley y nunca se efectuar\u00e1 un acto de abuso del poder.<\/div>\n<div>\u00a0<\/div>\n<div>Nota: Juan Pablo Pi\u00f1a ya reconoci\u00f3 que tendr\u00e1 que esperar a que concluya el pleito legal, es decir, la nulidad de la donaci\u00f3n onerosa, proceso que podr\u00eda llevarse hasta dos a\u00f1os para poder iniciar la construcci\u00f3n del parque metropolitano. Claro esto siempre y cuando se gane el juicio. Mientras tanto el gobierno no puede hacer ning\u00fan trabajo dentro del predio, \u00bfni siquiera regar los arbolitos que sembr\u00f3?<\/div>\n<div>\u00a0<\/div>\n<div><strong>alvarezenriqueta@hotmail.com<\/strong><\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El primer per\u00edodo de sesiones del Congreso local, termin\u00f3 con la farsa de la coalici\u00f3n \u201cCompromiso por Puebla\u201d. Las enormes diferencias ideol\u00f3gicas se hicieron patentes, al presentarse la iniciativa para la despenalizaci\u00f3n del aborto y la aceptaci\u00f3n de las sociedades en convivencia. Y para rematar se aprob\u00f3 la \u00faltima cuenta p\u00fablica de Mario Mar\u00edn. \u00a0 [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":422629,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390620","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390620"}],"version-history":[{"count":0,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390620\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media\/422629"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}