{"id":390621,"date":"2011-03-22T00:40:20","date_gmt":"2011-03-22T00:40:20","guid":{"rendered":"http:\/\/legacy-k2-2009-10688"},"modified":"2026-03-27T18:06:26","modified_gmt":"2026-03-28T00:06:26","slug":"udlap-trabaja-en-proyecto-para-eficientar-el-uso-de-energia-k2-10688","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/udlap-trabaja-en-proyecto-para-eficientar-el-uso-de-energia-k2-10688\/390621\/","title":{"rendered":"UDLAP trabaja en proyecto para eficientar el uso de energ\u00eda"},"content":{"rendered":"<div>La Universidad de las Am\u00e9ricas Puebla y la Appalachian State University (ASU), trabajan en conjunto para llevar a cabo actividades y proyectos que ayuden al uso eficiente de la Energ\u00eda.<\/div>\n<div>\u00a0<\/div>\n<div>Como parte de los proyectos, las dos instituciones est\u00e1n trabajando en lo relacionado a la producci\u00f3n de bio-diesel; el monitoreo de las emisiones de gases t\u00f3xicos en rellenos sanitarios para generaci\u00f3n de energ\u00eda el\u00e9ctrica; el uso de radiaci\u00f3n solar para calentamiento de agua, as\u00ed como en procesos fotovoltaicos para el tratamiento de agua industrial contaminada.<\/div>\n<div>\u00a0<\/div>\n<div>En trabajo colaborativo, se han realizado tres visitas de profesores de la facultad de ASU al campus de la UDLAP y viceversa a fin de detectar oportunidades para crear proyectos de investigaci\u00f3n as\u00ed como un programa dual de Maestr\u00eda en Energ\u00edas y Tecnolog\u00edas Sustentables.<\/div>\n<div>\u00a0<\/div>\n<div>En cuanto a las actividades, en d\u00edas pasados se organiz\u00f3 en la UDLAP la conferencia internacional en Adopci\u00f3n de Energ\u00edas Renovables en M\u00e9xico, en la cual profesores, estudiantes y profesionistas de diferentes partes de M\u00e9xico y del Continente Americano analizaron y discutieron temas como el futuro de la energ\u00eda e\u00f3lica y solar en M\u00e9xico; la investigaci\u00f3n en el uso de fuentes de energ\u00edas alternativas; pol\u00edticas y oportunidades de financiamiento para el uso de energ\u00edas limpias; tecnolog\u00edas y aplicaciones relacionadas con biocombustibles y biomasa; estad\u00edsticas sobre tendencias energ\u00e9ticas en el pa\u00eds y a nivel mundial; as\u00ed como las oportunidades que se tienen para incrementar la aplicaci\u00f3n de energ\u00edas renovables en M\u00e9xico.<\/div>\n<div>\u00a0<\/div>\n<div>Cabe destacar que este tipo de actividades y trabajo colaborativo con otras instituciones sirve de base para que la facultad y estudiantes de la UDLAP se involucren en actividades de investigaci\u00f3n y de desarrollo tecnol\u00f3gico en el campo de las Energ\u00edas Renovables.<\/div>\n<div>\u00a0<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Universidad de las Am\u00e9ricas Puebla y la Appalachian State University (ASU), trabajan en conjunto para llevar a cabo actividades y proyectos que ayuden al uso eficiente de la Energ\u00eda. \u00a0 Como parte de los proyectos, las dos instituciones est\u00e1n trabajando en lo relacionado a la producci\u00f3n de bio-diesel; el monitoreo de las emisiones de [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390621","post","type-post","status-publish","format-standard","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390621"}],"version-history":[{"count":1,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390621\/revisions"}],"predecessor-version":[{"id":428897,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390621\/revisions\/428897"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}