{"id":390627,"date":"2011-03-22T00:55:46","date_gmt":"2011-03-22T00:55:46","guid":{"rendered":"http:\/\/legacy-k2-2009-10694"},"modified":"2026-03-27T18:06:28","modified_gmt":"2026-03-28T00:06:28","slug":"no-mas-ambiciones-en-perjuicio-de-la-colectividad-senala-ardelio-vargas-k2-10694","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/no-mas-ambiciones-en-perjuicio-de-la-colectividad-senala-ardelio-vargas-k2-10694\/390627\/","title":{"rendered":"No m\u00e1s ambiciones en perjuicio de la colectividad, se\u00f1ala Ardelio Vargas"},"content":{"rendered":"<div>No m\u00e1s corrupci\u00f3n, tr\u00e1fico de influencias y malos servidores p\u00fablicos en el gobierno, pues se aplicar\u00e1 el estado de derecho, para evitar que se den m\u00e1s beneficios y ambiciones de car\u00e1cter personal en detrimento de la colectividad, sentenci\u00f3 el titular de la Secretar\u00eda de Seguridad P\u00fablica, Ardelio Vargas Fosado, durante la ceremonia oficial por el natalicio de Benito Ju\u00e1rez<\/div>\n<div>No m\u00e1s corrupci\u00f3n, tr\u00e1fico de influencias y malos servidores p\u00fablicos en el gobierno, pues se aplicar\u00e1 el estado de derecho, para evitar que se den m\u00e1s beneficios y ambiciones de car\u00e1cter personal en detrimento de la colectividad, sentenci\u00f3 el titular de la Secretar\u00eda de Seguridad P\u00fablica, Ardelio Vargas Fosado.<\/div>\n<div>\u00a0<\/div>\n<div>Este lunes en su discurso como orador oficial en la conmemoraci\u00f3n del 205 aniversario del natalicio de Benito Ju\u00e1rez, dijo que la presente administraci\u00f3n seguir\u00e1 el ejemplo del Benem\u00e9rito de las Am\u00e9ricas para dar soluciones que fortalezcan las instituciones, que en el caso de su secretar\u00eda ser\u00e1 garantizar la tranquilidad de los ciudadanos adem\u00e1s de contribuir a dar certidumbre para atraer nuevas inversiones.<\/div>\n<div>\u00a0<\/div>\n<div>Dijo que la sociedad demanda al nuevo gobierno mejorar los servicios de salud, educaci\u00f3n, crecimiento econ\u00f3mico, seguridad y gobernabilidad, para enfrentar los retos que exige la misma.<\/div>\n<div>\u00a0<\/div>\n<div>Frente al monumento de Benito Ju\u00e1rez, ubicado en el parque que lleva su nombre, del bulevar 5 de Mayo, al que asistieron representantes de los tres poderes del estado, Ardelio Vargas dijo que Puebla no est\u00e1 exenta de la ola de inseguridad que afecta al pa\u00eds, cuyos d\u00e9spotas de la delincuencia organizada, tiranos del narcotr\u00e1fico y generadores de violencia, son producto de la falta de aplicaci\u00f3n de pol\u00edticas p\u00fablicas que garanticen el estado de derecho, siendo en nuestra entidad que no se permitir\u00e1 que este tipo de criminalidad arrebate la tranquilidad de los que viven en ella.<\/div>\n<div>\u00a0<\/div>\n<div><\/div>\n<div>\u00a0<\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>No m\u00e1s corrupci\u00f3n, tr\u00e1fico de influencias y malos servidores p\u00fablicos en el gobierno, pues se aplicar\u00e1 el estado de derecho, para evitar que se den m\u00e1s beneficios y ambiciones de car\u00e1cter personal en detrimento de la colectividad, sentenci\u00f3 el titular de la Secretar\u00eda de Seguridad P\u00fablica, Ardelio Vargas Fosado, durante la ceremonia oficial por el [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390627","post","type-post","status-publish","format-standard","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390627"}],"version-history":[{"count":1,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390627\/revisions"}],"predecessor-version":[{"id":428902,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390627\/revisions\/428902"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}