{"id":390631,"date":"2011-03-22T02:08:33","date_gmt":"2011-03-22T02:08:33","guid":{"rendered":"legacy-k2-2009-10698"},"modified":"2011-03-22T02:08:33","modified_gmt":"2011-03-22T02:08:33","slug":"dudas-en-el-ajuste-de-cuentas-k2-10698","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/dudas-en-el-ajuste-de-cuentas-k2-10698\/390631\/","title":{"rendered":"Dudas en el ajuste de cuentas"},"content":{"rendered":"<div>\u00bfCu\u00e1ndo caer\u00e1 un pez gordo del marinismo?<\/div>\n<div>\u00a0<\/div>\n<div>Muchos poblanos se siguen preguntando si alg\u00fan miembro de la burbuja marinista ser\u00e1 llevado ante la justicia por el actual gobierno.<\/div>\n<div>\u00a0<\/div>\n<div>Parece sesgada la lectura que el gobierno poblano ha querido mostrar respecto de la recuperaci\u00f3n del predio de Valle Fant\u00e1stico. Bas\u00e1ndose en una encuesta publicada por un diario poblano, el gobierno ha difundido que su acci\u00f3n (la recuperaci\u00f3n del predio) es considerada positiva por los poblanos. \u00bfY qu\u00e9 esperaban? Era l\u00f3gico que la respuesta de la ciudadan\u00eda iba a ser positiva, pues la campa\u00f1a del gobierno del\u00a0Estado previa a la recuperaci\u00f3n del predio, as\u00ed como la percepci\u00f3n ciudadana -previa a la entrada en funciones del nuevo gobierno- era que Ricardo Henaine se hab\u00eda beneficiado de su relaci\u00f3n cercana con Mario Mar\u00edn y as\u00ed, por ese motivo, hab\u00eda alcanzado la posesi\u00f3n de los predios.<\/div>\n<div>\u00a0<\/div>\n<div>Resulta tambi\u00e9n parad\u00f3jico que sea el asesor legal del gobierno, Juan Pablo Pi\u00f1a, quien anuncie que el Gobierno del Estado ha recuperado los edificios donde operaba el diario El Heraldo, propiedad de Henaine, toda vez que el referido medio de comunicaci\u00f3n operaba en esas oficinas desde hace algunos sexenios, tanto que fue el padre del asesor legal, el ex-gobernador Pi\u00f1a Olaya, quien entreg\u00f3 ese predio en beneficio de los due\u00f1os de El Heraldo, en aquel tiempo la familia Alarc\u00f3n.\u00a0<\/div>\n<div>\u00a0<\/div>\n<div>Nadie duda que Henaine no debe tener el comodato indefinido de los edificios, pero no debe olvidarse que El Heraldo pose\u00eda ese predio desde el sexenio de Pi\u00f1a Olaya. Que hoy su hijo busque desvincular ese hecho, es cosa distinta.<\/div>\n<div>\u00a0<\/div>\n<div>Todo ello, pero sobre todo la falta de juzgamiento a los principales colaboradores de Mario Mar\u00edn, son algunas dudas que surgen del \u201cajuste de cuentas\u201d llevado a cabo por la actual administraci\u00f3n.<\/div>\n<div>\u00a0<\/div>\n<div>A Moreno Valle y su equipo se les reconoce que existan actos que hagan ingresar al patrimonio del Estado la posesi\u00f3n de predios, pero se le agradecer\u00e1, a\u00fan m\u00e1s, que no deje impunes los il\u00edcitos que tanto denunci\u00f3 durante su campa\u00f1a pol\u00edtica.<\/div>\n<div>\u00a0<\/div>\n<div>O, en todo caso, que nos diga si los il\u00edcitos que dijo comet\u00eda el marinismo no eran tales, sino una falsa percepci\u00f3n del morenovallismo.\u00a0<\/div>\n<div>\u00a0<\/div>\n<div>Que sean claros. La certeza se agradecer\u00e1.\u00a0<\/div>\n<div>\u00a0<\/div>\n<div>\u00bfEran o no eran delitos los cometidos por el marinismo?\u00a0<\/div>\n<div>\u00a0<\/div>\n<div>Si lo eran, \u00bfqui\u00e9nes son los culpables?\u00a0<\/div>\n<div>\u00a0<\/div>\n<div>Si no lo eran, ya sacaremos nuestras conclusiones.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfCu\u00e1ndo caer\u00e1 un pez gordo del marinismo? \u00a0 Muchos poblanos se siguen preguntando si alg\u00fan miembro de la burbuja marinista ser\u00e1 llevado ante la justicia por el actual gobierno. \u00a0 Parece sesgada la lectura que el gobierno poblano ha querido mostrar respecto de la recuperaci\u00f3n del predio de Valle Fant\u00e1stico. Bas\u00e1ndose en una encuesta publicada [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":422624,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390631","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390631"}],"version-history":[{"count":0,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390631\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media\/422624"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}