{"id":390649,"date":"2011-03-22T14:40:47","date_gmt":"2011-03-22T14:40:47","guid":{"rendered":"http:\/\/legacy-k2-2009-10718"},"modified":"2026-03-27T18:06:33","modified_gmt":"2026-03-28T00:06:33","slug":"marin-blindo-el-derroche-de-su-sexenio-por-12-anos-es-informacion-confidencial-k2-10718","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/marin-blindo-el-derroche-de-su-sexenio-por-12-anos-es-informacion-confidencial-k2-10718\/390649\/","title":{"rendered":"Mar\u00edn blind\u00f3 el derroche de su sexenio por 12 a\u00f1os; es \u201cinformaci\u00f3n confidencial\u201d"},"content":{"rendered":"<p>Antes de concluir su administraci\u00f3n, Mario Mar\u00edn Torres blind\u00f3 su despilfarro del sexenio, al clasificar como reservada por 12 a\u00f1os la informaci\u00f3n referente al uso de las cuatro l\u00edneas de cr\u00e9dito que solicit\u00f3 al Congreso local en 2005, 2006, 2008 y 2009, debido a un acuerdo de confidencialidad suscrito por el ex secretario de Finanzas y Administraci\u00f3n, Gerardo P\u00e9rez Salazar.<\/p>\n<p>A lo largo de su gobierno, Mario Mar\u00edn requiri\u00f3 cuatro l\u00edneas de cr\u00e9dito para el Poder Ejecutivo y los ayuntamientos por 9 mil millones de pesos en total, y una quinta l\u00ednea de cr\u00e9dito por 718 millones de pesos para uso exclusivo del Sistema Operador de los Servicios de Agua Potable y Alcantarillado de Puebla (SOAPAP). Sin embargo, el destino de los empr\u00e9stitos requeridos con la banca comercial se desconocen y, gracias al acuerdo del 16 de febrero de 2006, la informaci\u00f3n se mantendr\u00e1 como reservada por un periodo de 12 a\u00f1os.<\/p>\n<p>CAMBIO solicit\u00f3 a la Secretar\u00eda de Finanzas un desglose de los gastos realizados con las l\u00edneas de cr\u00e9dito, los estados de cuenta actuales, los intereses generados a lo largo de los a\u00f1os y el estado actual de la deuda p\u00fablica de la administraci\u00f3n estatal, y la respuesta fue que la informaci\u00f3n estaba reservada.<\/p>\n<p>\u201cSolicito un desglose de los gastos realizados por el gobierno de Mario Mar\u00edn Torres desde que inici\u00f3 su gesti\u00f3n en enero de 2005 hasta la fecha sobre las l\u00edneas de cr\u00e9dito contratadas con la banca comercial y que fueron aprobadas por el Congreso local en 2005,2007, 2008 y 2009. Requiero las tasas de inter\u00e9s y los a\u00f1os por los que fue contratada con la banca comercial; as\u00ed como los estados de cuenta de cada una de las l\u00edneas\u201d.<\/p>\n<p>En el 2005, la administraci\u00f3n marinista requiri\u00f3 una l\u00ednea de cr\u00e9dito por mil 500 millones de pesos; en el 2007 el Congreso local incluy\u00f3 en la Ley de Ingresos de ese a\u00f1o un empr\u00e9stito por 3 mil millones de pesos; en el 2008 se autoriz\u00f3 una l\u00ednea de cr\u00e9dito por 2 mil millones de pesos y, en el 2010, la administraci\u00f3n estatal hizo uso de un cr\u00e9dito por 2 mil 500 millones de pesos.<\/p>\n<p>La Secretar\u00eda de Finanzas respondi\u00f3 el pasado 18 de febrero a trav\u00e9s de la Unidad de Desarrollo Administrativo la clasificaci\u00f3n de la informaci\u00f3n y puso a disposici\u00f3n de esta casa editorial el acuerdo realizado por la administraci\u00f3n anterior.<\/p>\n<p>El acuerdo establece que las condiciones contractuales de los cr\u00e9ditos registrados en el Registro \u00danico de Obligaciones y Empr\u00e9stitos del Estado se encuentra en reserva por 12 a\u00f1os, basado en la Ley de Instituciones de Cr\u00e9dito que proh\u00edbe dar noticias o informaci\u00f3n de los servicios o cualquier tipo de operaciones, salvo que fueran requeridas por la autoridad con alguna orden judicial.<\/p>\n<p>El documento entregado a CAMBIO se\u00f1ala sobre los empr\u00e9stitos: \u201cEl desglose de los gastos de \u00e9stos es informaci\u00f3n clasificada como reservada en t\u00e9rminos del acuerdo de fecha 16 de febrero de 2006 suscrito por el entonces secretario de Finanzas y Administraci\u00f3n de conformidad con los art\u00edculos 2, fracci\u00f3n V, 11 y 12 fracci\u00f3n XII, 14 y 15 de la Ley de Transparencia y Acceso a la Informaci\u00f3n P\u00fablica\u201d.<\/p>\n<p>Sobre la tasa de inter\u00e9s y el estado de los cr\u00e9ditos se se\u00f1ala: \u201cHago de su conocimiento que el uso de los empr\u00e9stitos se destinan a inversiones p\u00fablicas productivas con base en lo se\u00f1alado por el art\u00edculo 8 de la Ley de Deuda P\u00fablica para el estado de Puebla, sin embargo, en lo referente a la tasa de inter\u00e9s y el a\u00f1o de contrataci\u00f3n es informaci\u00f3n clasificada como reservada en t\u00e9rminos del acuerdo de fecha 16 de febrero de 2006 suscrito por el entonces secretario de Finanzas y Administraci\u00f3n de conformidad con los art\u00edculos 2, fracci\u00f3n V, 11 y 12 fracci\u00f3n XII, 14 y 15 de la Ley de Transparencia y Acceso a la Informaci\u00f3n P\u00fablica.<\/p>\n<p>\u201cReferente a los estados de cuenta que solicita, se le comunica que dicha informaci\u00f3n se clasifica como reservada en t\u00e9rminos del acuerdo de fecha 16 de febrero de 2006 suscrito por el entonces secretario de Finanzas y Administraci\u00f3n de conformidad con los art\u00edculos 2, fracci\u00f3n V, 11 y 12 fracci\u00f3n XII, 14 y 15 de la Ley de Transparencia y Acceso a la Informaci\u00f3n P\u00fablica\u201d.<\/p>\n<p>Finalmente, sobre los estados de cuenta, la respuesta oficial se\u00f1ala lo siguiente: \u201cel pasado 21 de enero de 2011 se public\u00f3 en los diarios El Sol de Puebla y Excelsior el estado de la deuda p\u00fablica directa y contingente a cargo del gobierno y de los municipios y la informaci\u00f3n se encuentra disponible en el portal de internet <a href=\"http:\/\/www.transparenciafiscal.puebla.gob.mx\">www.transparenciafiscal.puebla.gob.mx<\/a>\u201d.<\/p>\n<p>Sin embargo, los links a los que hace referencia la respuesta no contienen la informaci\u00f3n solicitada. <br \/>\n&#160;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antes de concluir su administraci\u00f3n, Mario Mar\u00edn Torres blind\u00f3 su despilfarro del sexenio, al clasificar como reservada por 12 a\u00f1os la informaci\u00f3n referente al uso de las cuatro l\u00edneas de cr\u00e9dito que solicit\u00f3 al Congreso local en 2005, 2006, 2008 y 2009, debido a un acuerdo de confidencialidad suscrito por el ex secretario de Finanzas [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390649","post","type-post","status-publish","format-standard","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390649"}],"version-history":[{"count":1,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390649\/revisions"}],"predecessor-version":[{"id":428919,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390649\/revisions\/428919"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}