{"id":390652,"date":"2011-03-22T14:49:05","date_gmt":"2011-03-22T14:49:05","guid":{"rendered":"http:\/\/legacy-k2-2009-10721"},"modified":"2026-03-27T18:06:34","modified_gmt":"2026-03-28T00:06:34","slug":"gerardo-perez-salazar-el-siguiente-en-la-lista-negra-de-moreno-valle-k2-10721","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/gerardo-perez-salazar-el-siguiente-en-la-lista-negra-de-moreno-valle-k2-10721\/390652\/","title":{"rendered":"Gerardo P\u00e9rez Salazar, el siguiente en la lista negra de Moreno Valle"},"content":{"rendered":"<p>El&#160; ex secretario de Finanzas de la pasada administraci\u00f3n, Gerardo Mar\u00eda P\u00e9rez Salazar, muy pronto podr\u00eda estar viviendo un infierno similar al que vive hoy Ricardo Henaine Mezher.<\/p>\n<p>Para muchos testigos del proceso de transici\u00f3n, se trata del segundo lugar de la lista de \u201csacrificables\u201d pactada en las negociaciones entre autoridades electas y en funciones, previo a la toma de protesta de Rafael Moreno Valle como gobernador del estado.<\/p>\n<p>Lo anterior, no est\u00e1 basado en chismes o rumores, sino en un muy extenso expediente en poder del actual mandatario estatal, en donde se documentan operaciones irregulares realizadas por el funcionario en su paso por la administraci\u00f3n p\u00fablica local.<\/p>\n<p>Quienes conocen el detallado documento aseguran que es una aut\u00e9ntica chulada.<\/p>\n<p>Adem\u00e1s de comprobar diversos desv\u00edos que se operaron a trav\u00e9s de una serie de movimientos que para las actuales autoridades resultan por lo menos sospechosas, hay una parte espec\u00edfica de dicho reporte que ha llamado particularmente la atenci\u00f3n de Roberto Moya.<\/p>\n<p>Se trata de un apartado en donde se demuestra c\u00f3mo, por \u00f3rdenes de P\u00e9rez Salazar, se destinaron cerca de tres mil 500 millones de pesos del presupuesto estatal para realizar inversiones de alto riesgo, en un af\u00e1n de buscar una utilidad por los rendimientos potenciales de dichas inversiones.<\/p>\n<p>Monumental error.<\/p>\n<p>El resultado final de la ingeniosa estrategia financiera implementada por Gerardo Mar\u00eda fue un rotundo fracaso.<\/p>\n<p>Las inversiones, lejos de ser rentables, generaron p\u00e9rdidas cercanas a los 180 millones.<\/p>\n<p>Desafortunadamente para \u00e9l, la historia no se agota aqu\u00ed.<\/p>\n<p>Existen agravantes adicionales que complican a\u00fan m\u00e1s su situaci\u00f3n.<\/p>\n<p>Resulta que todas, absolutamente todas las inversiones realizadas por el entonces funcionario, tal y como ya se sab\u00eda, fueron destinadas a Vector, casa de cambio que no s\u00f3lo fue dirigida en su momento por el propio P\u00e9rez Salazar, sino que tiene como ejecutivo estrella a Margarita Rojas, actual esposa del propio funcionario y quien tiene en los hechos la titularidad indiscutible de la cuenta del Gobierno del Estado.<\/p>\n<p>M\u00e1s all\u00e1 de que en los registros oficiales de la instancia financiera pudiera aparecer otro ejecutivo como quien maneja la cuenta, entre los mismos empleados de Vector es un secreto a voces que quien realmente cobraba cada peso de las comisiones que se generaban por el manejo de la voluminosa cuenta era la esposa del ahora ex funcionario marinista.<\/p>\n<p>Negocio familiar redondo a costa de p\u00e9rdidas millonarias para el dinero de todos los poblanos.<\/p>\n<p>En este contexto, no resulta extra\u00f1o el hecho de que P\u00e9rez Salazar, cuando no hab\u00edan pasado siquiera doce horas a partir del momento en el que las empresas encuestadoras daban a conocer a la opini\u00f3n p\u00fablica los resultados de sus encuestas de salida aplicadas en territorio poblano el pasado 4 de julio, hab\u00eda ya puesto sobre el escritorio del gobernador su renuncia como servidor p\u00fablico.<\/p>\n<p>Mario Mar\u00edn no se la acept\u00f3 y de paso lo comprometi\u00f3 a permanecer en su cargo hasta el \u00faltimo d\u00eda del sexenio.<\/p>\n<p>Gerardo Mar\u00eda sab\u00eda, mejor que nadie, lo que se hab\u00eda tragado.<\/p>\n<p>Adem\u00e1s, estaba consciente de que podr\u00eda, al igual que Henaine, convertirse f\u00e1cilmente en moneda de cambio de la negociaci\u00f3n pol\u00edtica que se dio en el largu\u00edsimo proceso de transici\u00f3n.<\/p>\n<p>Hoy, todo parece indicar que los miedos de Gerardo Mar\u00eda podr\u00edan traducirse en el inicio de una serie de procedimientos legales en su contra que podr\u00edan, desde inhabilitarlo para volver a ocupar un cargo p\u00fablico, hasta probarse aquel traje caqui tan de moda en San Miguel.<\/p>\n<p>&#160;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El&#160; ex secretario de Finanzas de la pasada administraci\u00f3n, Gerardo Mar\u00eda P\u00e9rez Salazar, muy pronto podr\u00eda estar viviendo un infierno similar al que vive hoy Ricardo Henaine Mezher. Para muchos testigos del proceso de transici\u00f3n, se trata del segundo lugar de la lista de \u201csacrificables\u201d pactada en las negociaciones entre autoridades electas y en funciones, [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390652","post","type-post","status-publish","format-standard","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390652"}],"version-history":[{"count":1,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390652\/revisions"}],"predecessor-version":[{"id":428922,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390652\/revisions\/428922"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}