{"id":390673,"date":"2011-03-23T00:31:55","date_gmt":"2011-03-23T00:31:55","guid":{"rendered":"http:\/\/legacy-k2-2009-10742"},"modified":"2026-03-27T18:06:39","modified_gmt":"2026-03-28T00:06:39","slug":"ibero-puebla-sede-de-la-muestra-artistica-de-derzu-campos-k2-10742","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/ibero-puebla-sede-de-la-muestra-artistica-de-derzu-campos-k2-10742\/390673\/","title":{"rendered":"IBERO Puebla, sede de la muestra art\u00edstica de Derzu Campos"},"content":{"rendered":"<div>La expresi\u00f3n es un motor para la creaci\u00f3n, el dinero, otro. Esta dualidad del trabajo del artista se presenta en la exposici\u00f3n \u201cINSIDE\/OUTSIDE, Obra art\u00edstica y trabajo por dinero\u201d, primera muestra individual de Derzu Campos, becario del programa J\u00f3venes Creadores 2010-11 (FONCA, M\u00e9xico, DF), que ser\u00e1 inaugurada en la Universidad Iberoamericana Puebla el mi\u00e9rcoles 23 de marzo a las 19:00 horas en la Galer\u00eda ubicada en la Biblioteca de la instituci\u00f3n.<\/div>\n<div><\/div>\n<div>\u201cPor un lado [est\u00e1] mi obra personal, mis mundos interiores, mis inquietudes art\u00edsticas y conceptuales; y por el otro, el trabajo remunerado, por encargo, venido desde fuera, hecho para otros y a gusto de otros. El mundo interno y el mundo externo, el yo y el otro, dentro, fuera: inside, outside\u201d, se\u00f1ala Campos.<\/div>\n<div><\/div>\n<div>A sus 30 a\u00f1os, este multifac\u00e9tico artista visual \u00ad\u00beque es tambi\u00e9n cineasta, m\u00fasico y fot\u00f3grafo\u00be se encuentra entre los mejores ilustradores en el \u00e1mbito mundial, de acuerdo al libro 200 Best Illustrators worldwide 10\/11, publicado por la editorial internacional L\u00fcrzer&#8217;s ARCHIVE. Campos ha participado en numerosas exposiciones colectivas en M\u00e9xico y el extranjero, y trabajado para diversas editoriales, revistas, canales de televisi\u00f3n y medios electr\u00f3nicos. Entre sus clientes se cuentan la editorial Santillana, TV3 canal de Catalu\u00f1a, la disquera Nuevos Ricos y las revistas Letras Libres, Replicante, Solario e IndieRocks!, entre otras.<\/div>\n<div><\/div>\n<div>Derzu Campos naci\u00f3 en 1980 en Culiac\u00e1n, Sinaloa. \u00a0Estudi\u00f3 Dise\u00f1o de la Comunicaci\u00f3n Gr\u00e1fica en el Universidad Aut\u00f3noma Metropolitana, ilustraci\u00f3n en la EINA, Escola de Disseni i Art, en Barcelona, Espa\u00f1a, y Artes Visuales en la academia Gerrit Rietveld, en \u00c1msterdam, Holanda.<\/div>\n<div><\/div>\n<div>La exposici\u00f3n \u201cINSIDE\/OUTSIDE\u201d permanecer\u00e1 en la Galer\u00eda de la Ibero-Puebla hasta el s\u00e1bado 14 de mayo, abierta de lunes a viernes de 7:00 a 21:00 horas y los s\u00e1bados 9:00 a 15:00 horas. La entrada es gratuita.<\/div>\n<div><\/div>\n<div>Para m\u00e1s informaci\u00f3n, comunicarse a Difusi\u00f3n Universitaria al tel\u00e9fono 372 30 58 o al correo electr\u00f3nico carolina.martinez@iberopuebla.edu.mx.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La expresi\u00f3n es un motor para la creaci\u00f3n, el dinero, otro. Esta dualidad del trabajo del artista se presenta en la exposici\u00f3n \u201cINSIDE\/OUTSIDE, Obra art\u00edstica y trabajo por dinero\u201d, primera muestra individual de Derzu Campos, becario del programa J\u00f3venes Creadores 2010-11 (FONCA, M\u00e9xico, DF), que ser\u00e1 inaugurada en la Universidad Iberoamericana Puebla el mi\u00e9rcoles 23 [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390673","post","type-post","status-publish","format-standard","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390673"}],"version-history":[{"count":1,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390673\/revisions"}],"predecessor-version":[{"id":428937,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390673\/revisions\/428937"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}