{"id":390679,"date":"2011-03-23T01:11:56","date_gmt":"2011-03-23T01:11:56","guid":{"rendered":"http:\/\/legacy-k2-2009-10748"},"modified":"2026-03-27T18:06:40","modified_gmt":"2026-03-28T00:06:40","slug":"san-andres-cholula-conmemoro-el-dia-mundial-del-agua-k2-10748","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/san-andres-cholula-conmemoro-el-dia-mundial-del-agua-k2-10748\/390679\/","title":{"rendered":"San Andr\u00e9s Cholula conmemor\u00f3 el D\u00eda Mundial del Agua"},"content":{"rendered":"<div>Autoridades municipales celebraron el D\u00eda Mundial del Agua, en compa\u00f1\u00eda de estudiantes de escuelas aleda\u00f1as al municipio qui\u00e9nes participaron en el Concurso de Oratoria y Dibujo efectuado para conmemorar este d\u00eda.<\/div>\n<div><\/div>\n<div>Por su parte y en representaci\u00f3n del Pdte. Municipal Lic. Miguel \u00c1ngel Huepa P\u00e9rez, el regidor de gobernaci\u00f3n Jes\u00fas Romero Toxqui destac\u00f3 la importancia de crear conciencia en las nuevas generaciones sobre la importancia que tiene el cuidado del agua.<\/div>\n<div><\/div>\n<div>Agreg\u00f3 que es necesario realizar campa\u00f1as que concienticen a los ni\u00f1os, j\u00f3venes, adultos y personas mayores, sobre la responsabilidad compartida para cuidar este vital l\u00edquido para la vida.<\/div>\n<div><\/div>\n<div>Con la participaci\u00f3n de m\u00e1s de 51 j\u00f3venes estudiantes de diferentes Instituciones Educativas del municipio, se realiz\u00f3 el Concurso de Oratoria y Dibujo alusivo al D\u00eda Mundial del Agua que este a\u00f1o lleva por lema \u201cAgua para las Ciudades: respondiendo al desaf\u00edo urbano\u201d.\u00a0<\/div>\n<div><\/div>\n<div>De esta manera autoridades realizaron la entrega de reconocimientos y constancias de participaci\u00f3n a los estudiantes que, de manera activa participaron en alguno de los concursos alusivos a este importante d\u00eda.<\/div>\n<div><\/div>\n<div>Tan solo el 3% del agua del planeta es dulce, y de ese 3% solo la mitad es potable, de ah\u00ed la importancia de iniciar de manera inmediata las acciones de concientizaci\u00f3n, puntualizaron autoridades.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Autoridades municipales celebraron el D\u00eda Mundial del Agua, en compa\u00f1\u00eda de estudiantes de escuelas aleda\u00f1as al municipio qui\u00e9nes participaron en el Concurso de Oratoria y Dibujo efectuado para conmemorar este d\u00eda. Por su parte y en representaci\u00f3n del Pdte. Municipal Lic. Miguel \u00c1ngel Huepa P\u00e9rez, el regidor de gobernaci\u00f3n Jes\u00fas Romero Toxqui destac\u00f3 la importancia [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390679","post","type-post","status-publish","format-standard","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390679"}],"version-history":[{"count":1,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390679\/revisions"}],"predecessor-version":[{"id":428940,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390679\/revisions\/428940"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}