{"id":390711,"date":"2011-03-23T14:03:02","date_gmt":"2011-03-23T14:03:02","guid":{"rendered":"http:\/\/legacy-k2-2009-10780"},"modified":"2026-03-27T18:06:49","modified_gmt":"2026-03-28T00:06:49","slug":"salida-de-cruz-perez-no-acaba-con-corrupcion-en-ceresos-de-puebla-k2-10780","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/salida-de-cruz-perez-no-acaba-con-corrupcion-en-ceresos-de-puebla-k2-10780\/390711\/","title":{"rendered":"Salida de Cruz P\u00e9rez no acaba con corrupci\u00f3n en Ceresos de Puebla"},"content":{"rendered":"<p>A un d\u00eda de vencido el plazo fijado por la Comisi\u00f3n de los Derechos Humanos (CDH), al secretario de Seguridad P\u00fablica del Estado, Ardelio Vargas Fosado, que requer\u00eda instruyera al director de los Centros de Readaptaci\u00f3n Social de Puebla, Aldo Enrique Cruz P\u00e9rez, de abstenerse de externar comentarios que induzcan a afectar la dignidad de las personas \u2014por sus comentarios homof\u00f3bicos sobre los matrimonios del mismo sexo\u2014, el director de los Ceresos \u201cMonse\u00f1or Aldo\u201d, le fue aceptada su renuncia \u201cpor motivos personales\u201d, adem\u00e1s de que otro de sus m\u00e1s cercanos colaboradores, Edmundo Rams\u00e9s Casta\u00f1\u00f3n Amaro, tuvo que presentar el mismo documento y tambi\u00e9n le fue aceptado.<\/p>\n<p>La renuncia de Aldo Enrique, que entre l\u00edneas se lee \u201cest\u00e1 usted despedido\u201d, termina con una era de oscurantismo al interior de los Centros de Readaptaci\u00f3n, con una cadena de abusos de autoridad y de actos de corrupci\u00f3n, por no decir tr\u00e1fico de drogas, contrabando, tr\u00e1fico de influencias y otros m\u00e1s que pusieron en las p\u00e1ginas negras los sistemas de readaptaci\u00f3n poblano y que provocaron que al interior de las prisiones poblanas se entretejieran nexos con el crimen organizado.<\/p>\n<p>Aldo Enrique, el hombre \u2014que fuera de s\u00ed\u2014 pate\u00f3 en varias ocasiones el cesto de basura del ahora exsecretario de Seguridad, general Mario Ay\u00f3n, para demostrarle su fuerza pol\u00edtica y que no pod\u00eda despedirlo, en estos momentos debe de estar preparando todos sus mecanismos de defensa, porque va a ser acusado de cometer muchos abusos no s\u00f3lo a personal de seguridad y custodia, sino a los mismos internos a quienes afect\u00f3 al permitir el ejercicio de delitos al interior de penales, como la venta de protecci\u00f3n, el caso omiso de la operatividad de grupos delictivos que perpetraban chantajes a trav\u00e9s de tel\u00e9fonos que les permit\u00edan tener venta de drogas de todos los tipos, adem\u00e1s de \u201ccomo en los tiempos de la mafia italiana\u201d, \u201cpermisos\u201d para la renta de televisores, de habitaciones cinco estrellas al internos que pod\u00edan pagar 15 mil pesos al mes y muchos y muchos excesos que otorga el poder ilimitado.<\/p>\n<p>La salida de \u201cMonse\u00f1or Aldo\u201d, no termina la corrupci\u00f3n que impera en los centros de readaptaci\u00f3n, debe de hacerse como consecuencia una limpia, de entrada terminar de tajo con los privilegios, en todo el estado de presos que deben de ser sujetos a una readaptaci\u00f3n en lo que duran sus condenas y no cobrarles protecci\u00f3n para que estos erijan imperios delictivos.<\/p>\n<p>Centros de readaptaci\u00f3n como el de Puebla, deben de ser objeto de una concienzuda revisi\u00f3n, desde los permisos para la venta de comida, refrescos \u2014negocio monopolizado a una sola empresa\u2014, hasta las habitaciones de lujo donde viven delincuentes que pagan fuertes sumas de dinero para no mezclarse con la poblaci\u00f3n de procesados y de sentenciados.<\/p>\n<p>De esta limpia vamos a estar muy pendientes.<br \/>\n&#160;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A un d\u00eda de vencido el plazo fijado por la Comisi\u00f3n de los Derechos Humanos (CDH), al secretario de Seguridad P\u00fablica del Estado, Ardelio Vargas Fosado, que requer\u00eda instruyera al director de los Centros de Readaptaci\u00f3n Social de Puebla, Aldo Enrique Cruz P\u00e9rez, de abstenerse de externar comentarios que induzcan a afectar la dignidad de [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390711","post","type-post","status-publish","format-standard","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390711"}],"version-history":[{"count":1,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390711\/revisions"}],"predecessor-version":[{"id":428965,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390711\/revisions\/428965"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}