{"id":390719,"date":"2011-03-23T21:13:56","date_gmt":"2011-03-23T21:13:56","guid":{"rendered":"http:\/\/legacy-k2-2009-10788"},"modified":"2026-03-27T18:06:52","modified_gmt":"2026-03-28T00:06:52","slug":"udlap-estudiantes-podran-realizar-practias-profesionales-en-the-washington-center-k2-10788","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/udlap-estudiantes-podran-realizar-practias-profesionales-en-the-washington-center-k2-10788\/390719\/","title":{"rendered":"UDLAP, estudiantes podr\u00e1n realizar pr\u00e1cticas profesionales en The Washington Center"},"content":{"rendered":"<p>Estudiantes de la Universidad de las Am\u00e9ricas Puebla recibieron la visita de un representante de The Washington Center quien les inform\u00f3 sobre la oportunidad que les brinda este organismo para realizar pr\u00e1cticas profesionales en una instituci\u00f3n internacional. \u201cLes estamos brindando la oportunidad a estudiantes de Derecho, Relaciones Internacionales, Negocios, Finanzas, entre otras licenciaturas de la UDLAP, de obtener experiencia laboral a nivel internacional mediante pr\u00e1cticas profesionales, mejorando con ello su curr\u00edculum y su profesi\u00f3n\u201d, afirm\u00f3 Luisa Solarte, gerente general de Reclutamiento Internacional para The Washington Center.<\/p>\n<p>Explic\u00f3 que adem\u00e1s de sus realizar pr\u00e1cticas profesionales en una organizaci\u00f3n internacional durante un semestre, los estudiantes de la UDLAP aceptados tomar\u00e1n un curso acad\u00e9mico y tendr\u00e1n acceso a ponencias con personalidades muy importantes a nivel internacional quienes hablar\u00e1n de temas relevantes e importantes que les ayudar\u00e1n en su desarrollo profesional.<\/p>\n<p>Sobre el n\u00famero de estudiantes aceptados, la Gerente General de Reclutamiento Internacional para The Washington Center dijo que actualmente no se cuenta con un l\u00edmite de lugares; \u201cpor lo regular recibimos cinco estudiantes por semestre pero este a\u00f1o tenemos el objetivo de incrementar estos lugares y ofrecerles esta oportunidad a m\u00e1s estudiantes de la UDLAP\u201d, destac\u00f3 Luisa Solarte.<\/p>\n<p>Inform\u00f3 que los requisitos que deben cubrir los estudiantes aceptados son: estar cursando del cuarto semestre en adelante, tener promedio de m\u00e1s de 80 y 550 puntos en el examen TOEFEL, realizar un ensayo del tema en al que se quieren dedicar durante sus pr\u00e1cticas, describir por qu\u00e9 quieren realizar sus pr\u00e1cticas profesionales en The Washington Center y entregar dos cartas de recomendaci\u00f3n.<\/p>\n<p>Finalmente coment\u00f3 que esta convocatoria se lanza a s\u00f3lo tres universidades de M\u00e9xico \u201ccon las cuales tenemos acuerdos fuertes de colaboraci\u00f3n por ambas partes, entre las que destaca la UDLAP\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estudiantes de la Universidad de las Am\u00e9ricas Puebla recibieron la visita de un representante de The Washington Center quien les inform\u00f3 sobre la oportunidad que les brinda este organismo para realizar pr\u00e1cticas profesionales en una instituci\u00f3n internacional. \u201cLes estamos brindando la oportunidad a estudiantes de Derecho, Relaciones Internacionales, Negocios, Finanzas, entre otras licenciaturas de la [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390719","post","type-post","status-publish","format-standard","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390719"}],"version-history":[{"count":1,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390719\/revisions"}],"predecessor-version":[{"id":428970,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390719\/revisions\/428970"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}