{"id":390720,"date":"2011-03-23T21:17:17","date_gmt":"2011-03-23T21:17:17","guid":{"rendered":"http:\/\/legacy-k2-2009-10789"},"modified":"2026-03-27T18:06:53","modified_gmt":"2026-03-28T00:06:53","slug":"instituto-de-ciencias-buap-sede-de-simposio-de-deteccion-de-microorganismos-k2-10789","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/instituto-de-ciencias-buap-sede-de-simposio-de-deteccion-de-microorganismos-k2-10789\/390720\/","title":{"rendered":"Instituto de Ciencias BUAP, sede de simposio de Detecci\u00f3n de Microorganismos"},"content":{"rendered":"<p>El Centro de Investigaci\u00f3n en Ciencias Microbiol\u00f3gicas, del Instituto de Ciencias (ICUAP) de la BUAP, realizar\u00e1 el Segundo Simposio Nacional de Detecci\u00f3n de Microorganismos, donde participar\u00e1n especialistas de la Instituci\u00f3n, as\u00ed como el Instituto Polit\u00e9cnico Nacional y la Universidad Aut\u00f3noma Benito Ju\u00e1rez de Oaxaca, entre otras instituciones, quienes disertar\u00e1n sobre las diferentes herramientas y t\u00e9cnicas, para la detecci\u00f3n de microorganismos en el ambiente, los alimentos y el hombre.<\/p>\n<p>La maestra en ciencias Edith Ch\u00e1vez Bravo, investigadora del ICUAP inform\u00f3 que este Simposio que se llevar\u00e1 a cabo el pr\u00f3ximo 7 de abril, de 14:00 a 21:00 horas, en el auditorio Ingeniero Antonio Osorio Garc\u00eda, de la Facultad de Ingenier\u00eda, en Ciudad Universitaria, es abierto a estudiantes, docentes e investigadores interesados en la materia, que podr\u00e1n participar como asistentes o ponentes.<\/p>\n<p>La finalidad de este evento es que \u201cexista una complementariedad e interdisciplinariedad entre diferentes disciplinas cient\u00edficas vinculadas con microorganismos, como biolog\u00eda o qu\u00edmica\u201d.<\/p>\n<p>Actualmente, puntualiz\u00f3 la investigadora, la detecci\u00f3n de microorganismos como bacterias, hongos, par\u00e1sitos y virus, constituye una herramienta esencial a nivel cl\u00ednico para el r\u00e1pido diagn\u00f3stico de afecciones, \u201cy contribuye en la reducci\u00f3n del alto consumo de antibi\u00f3ticos que ya est\u00e1\u00a0 presentando un problema a nivel nacional\u201d.<\/p>\n<p>Los interesados en participar con proyectos de investigaci\u00f3n, ya sea en ponencias o a trav\u00e9s de carteles, pueden\u00a0 enviar sus propuestas especificando la tem\u00e1tica: detecci\u00f3n de microorganismos en alimentos, \u00e1rea m\u00e9dica o ambiental, al correo\u00a0 electr\u00f3nico deteccion_mo@yahoo.com, antes del 30 de marzo.<\/p>\n<p>Este Simposio tiene valor curricular y su costo es de 150 pesos para estudiantes y\u00a0 250 pesos para profesionistas, cuota que deber\u00e1n depositar en la cuenta n\u00famero 400093838-1 del banco HSBC.<\/p>\n<p>El comprobante de pago se entregar\u00e1 en el Centro de Investigaci\u00f3n en Ciencias Microbiol\u00f3gicas, en Ciudad Universitaria, o bien escaneado al correo electr\u00f3nico lewimx@yahoo.com.mx. Mayores informes o inscripciones al 2 29 55 00 extensiones 2540 o 2544.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Centro de Investigaci\u00f3n en Ciencias Microbiol\u00f3gicas, del Instituto de Ciencias (ICUAP) de la BUAP, realizar\u00e1 el Segundo Simposio Nacional de Detecci\u00f3n de Microorganismos, donde participar\u00e1n especialistas de la Instituci\u00f3n, as\u00ed como el Instituto Polit\u00e9cnico Nacional y la Universidad Aut\u00f3noma Benito Ju\u00e1rez de Oaxaca, entre otras instituciones, quienes disertar\u00e1n sobre las diferentes herramientas y t\u00e9cnicas, [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390720","post","type-post","status-publish","format-standard","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390720"}],"version-history":[{"count":1,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390720\/revisions"}],"predecessor-version":[{"id":428971,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390720\/revisions\/428971"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}