{"id":390726,"date":"2011-03-23T21:39:24","date_gmt":"2011-03-23T21:39:24","guid":{"rendered":"http:\/\/legacy-k2-2009-10795"},"modified":"2026-03-27T18:06:54","modified_gmt":"2026-03-28T00:06:54","slug":"moreno-valle-acudio-a-la-presentacion-de-la-agenda-del-agua-2030-k2-10795","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/moreno-valle-acudio-a-la-presentacion-de-la-agenda-del-agua-2030-k2-10795\/390726\/","title":{"rendered":"Moreno Valle acudi\u00f3 a la presentaci\u00f3n de la Agenda del Agua 2030"},"content":{"rendered":"<p>Al asistir a la ceremonia de presentaci\u00f3n de la Agenda del Agua 2030 que  encabez\u00f3 el Presidente Felipe Calder\u00f3n Hinojosa, el Gobernador Rafael  Moreno Valle\u00a0 se\u00f1al\u00f3 que su administraci\u00f3n invertir\u00e1 m\u00e1s de mil 500  millones de pesos en proyectos de saneamiento de r\u00edos, lagos,  tratamiento de aguas residuales y para asegurar el abasto de agua  potable en beneficio de los poblanos<\/p>\n<p>Al asistir a la ceremonia de presentaci\u00f3n de la Agenda del Agua 2030 que encabez\u00f3 el Presidente Felipe Calder\u00f3n Hinojosa, el Gobernador Rafael Moreno Valle\u00a0 se\u00f1al\u00f3 que su administraci\u00f3n invertir\u00e1 m\u00e1s de mil 500 millones de pesos en proyectos de saneamiento de r\u00edos, lagos, tratamiento de aguas residuales y para asegurar el abasto de agua potable en beneficio de los poblanos.<\/p>\n<p>El Mandatario estatal dijo que el saneamiento del lago de Valsequillo es uno de los proyectos que emprender\u00e1 su administraci\u00f3n para recuperar\u00a0 uno de los m\u00e1s importantes afluentes que existen en la entidad.<\/p>\n<p>Record\u00f3 que los recursos naturales no son una herencia de nuestros padres para dilapidarlos, sino representan el patrimonio de las nuevas generaciones que debemos cuidar y preservar.<\/p>\n<p>Moreno Valle indic\u00f3 que su gobierno coincide en los objetivos que fija la Agenda del Agua 2030 en el sentido de evitar en los pr\u00f3ximos a\u00f1os un \u201cstress h\u00eddrico\u201d como consecuencia de la sobreexplotaci\u00f3n de los mantos acu\u00edferos.<\/p>\n<p>Por eso estamos trabajando, tambi\u00e9n, con los ayuntamientos para reforestar los bosques que son una fuente generadora de agua, as\u00ed como en coinversiones para construir nuevas plantas de tratamiento y en varios proyectos para presas en la mixteca y la sierra norte donde se presentan problemas de escasez del vital l\u00edquido.<\/p>\n<p>Rafael Moreno Valle calific\u00f3 como significativo el esfuerzo que lidera el Presidente Calder\u00f3n para tomar acciones de largo plazo a fin de cuidar el agua.<\/p>\n<p>Durante mucho tiempo, advirti\u00f3, ha habido\u00a0 una pol\u00edtica de consumo irracional de este recurso natural con la percepci\u00f3n de que va a durar para siempre, lo cual no es real, por ello los tres niveles de gobierno y la sociedad civil han acordado sumar esfuerzos para realizar campa\u00f1as hacia los hogares y otros lugares que contribuyan a garantizar el cuidado y abasto de este elemento.<\/p>\n<p>En este evento el Presidente de la Rep\u00fablica\u00a0 enfatiz\u00f3 que la Agenda 2030 sienta las bases para una soluci\u00f3n eficaz para que los mexicanos cuenten con agua en cantidad y calidad suficientes. El cuidado de este recurso, recalc\u00f3, es una tarea permanente de todos.<\/p>\n<p>Las principales metas de la Agenda del Agua en las pr\u00f3ximas dos d\u00e9cadas son r\u00edos y lagos limpios, mantener el equilibrio en cuencas y acu\u00edferos, cobertura universal de agua y alcantarillado, y asentamientos seguros ante embates -inundaciones- por el cambio clim\u00e1tico.<br \/>Adem\u00e1s del gobernador de Puebla, asistieron los mandatarios de Yucat\u00e1n, Campeche, Colima, Morelos, Oaxaca, Quer\u00e9taro, Sinaloa, Chihuahua, Nuevo Le\u00f3n, Sonora y Veracruz. Tambi\u00e9n estuvieron presentes alcaldes, rectores de universidades, empresarios y representantes de otros sectores de la sociedad mexicana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al asistir a la ceremonia de presentaci\u00f3n de la Agenda del Agua 2030 que encabez\u00f3 el Presidente Felipe Calder\u00f3n Hinojosa, el Gobernador Rafael Moreno Valle\u00a0 se\u00f1al\u00f3 que su administraci\u00f3n invertir\u00e1 m\u00e1s de mil 500 millones de pesos en proyectos de saneamiento de r\u00edos, lagos, tratamiento de aguas residuales y para asegurar el abasto de agua [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":422598,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390726","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390726"}],"version-history":[{"count":1,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390726\/revisions"}],"predecessor-version":[{"id":428975,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390726\/revisions\/428975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media\/422598"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}