{"id":390739,"date":"2011-03-24T00:59:47","date_gmt":"2011-03-24T00:59:47","guid":{"rendered":"http:\/\/legacy-k2-2009-10808"},"modified":"2026-03-27T18:06:57","modified_gmt":"2026-03-28T00:06:57","slug":"constructor-perecio-electrocutado-en-tepanco-k2-10808","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/constructor-perecio-electrocutado-en-tepanco-k2-10808\/390739\/","title":{"rendered":"Constructor pereci\u00f3 electrocutado en Tepanco"},"content":{"rendered":"<div>Hombre pereci\u00f3 tras hacer de una altura de 8 metros de altura cuando se encontraba armando estructuras de una granja, hechos registrados en la zona de Tepanco de L\u00f3pez, perteneciente a Tehuac\u00e1n.<\/div>\n<div><\/div>\n<div>El occiso responde al nombre de Vicente Ram\u00edrez Garc\u00eda, de 28 a\u00f1os de edad, quien de acuerdo a la versi\u00f3n de su esposa, el infortunado hab\u00eda sido contratado para trabajar en la edificaci\u00f3n de una granja, por lo que inici\u00f3 la colocaci\u00f3n de unas estructuras en el techo, siendo en ese momento cuando tropez\u00f3 con una viga y cay\u00f3 \u00a0de una altura de 8 metros.\u00a0<\/div>\n<div><\/div>\n<div>Aun con lesiones graves en el cr\u00e1neo, el accidentado fue trasladado a la cl\u00ednica n\u00famero 15 del IMSS donde finalmente pereci\u00f3 y los hechos quedaron asentados en la constancia 394\/2011\/TEHUAC\u00c1N<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hombre pereci\u00f3 tras hacer de una altura de 8 metros de altura cuando se encontraba armando estructuras de una granja, hechos registrados en la zona de Tepanco de L\u00f3pez, perteneciente a Tehuac\u00e1n. El occiso responde al nombre de Vicente Ram\u00edrez Garc\u00eda, de 28 a\u00f1os de edad, quien de acuerdo a la versi\u00f3n de su esposa, [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390739","post","type-post","status-publish","format-standard","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390739"}],"version-history":[{"count":1,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390739\/revisions"}],"predecessor-version":[{"id":428984,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390739\/revisions\/428984"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}