{"id":390742,"date":"2011-03-24T01:05:16","date_gmt":"2011-03-24T01:05:16","guid":{"rendered":"http:\/\/legacy-k2-2009-10811"},"modified":"2026-03-27T18:06:59","modified_gmt":"2026-03-28T00:06:59","slug":"rivera-advierte-que-nuevos-mandos-en-transito-estan-a-prueba-k2-10811","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/rivera-advierte-que-nuevos-mandos-en-transito-estan-a-prueba-k2-10811\/390742\/","title":{"rendered":"Rivera advierte que nuevos mandos en Tr\u00e1nsito est\u00e1n a prueba"},"content":{"rendered":"<div>El edil de Puebla, Eduardo Rivera P\u00e9rez, asegur\u00f3 que los nuevos mandos de Tr\u00e1nsito municipal est\u00e1n a prueba pues deben demostrar que son garant\u00eda de que no habr\u00e1 corrupci\u00f3n<\/div>\n<div>Para el alcalde de Puebla, Eduardo Rivera P\u00e9rez, los comentarios respecto a la vinculaci\u00f3n que podr\u00eda existir entre los mandos medios que fueron relevados y los que ahora ocupan su puesto son infundados, al enfatizar que son posiciones temporales que est\u00e1n siendo evaluadas<\/div>\n<div><\/div>\n<div>\u201cLos comentarios no est\u00e1n fundados, porque los nombramientos no son permanentes y est\u00e1n sujetos a evaluaci\u00f3n constante, al contrario es una acci\u00f3n in\u00e9dita y reitero, la vigilancia a la eficiencia y el combate a la corrupci\u00f3n en los cuerpos policiales ser\u00e1 permanente\u201d, indic\u00f3.<\/div>\n<div><\/div>\n<div><strong>PIDE A LOS PARTIDOS NO METERSE EN EL PROCESO<\/strong><\/div>\n<div><\/div>\n<div>En otro tema, el alcalde capitalino lanz\u00f3 un exhorto a los partidos pol\u00edticos para no enturbiar el proceso de elecci\u00f3n de presidentes en las juntas auxiliares, esto despu\u00e9s de que el priista Javier \u00a0L\u00f3pez Zavala reconociera su injerencia en el proceso de selecci\u00f3n de candidatos.<\/div>\n<div><\/div>\n<div>Rivera P\u00e9rez evit\u00f3 polemizar m\u00e1s en el tema al asegurar que no es un representante pol\u00edtico sino un alcalde, por lo que rechaz\u00f3 responder a las declaraciones del priista quien acus\u00f3 favoritismos para los candidatos que impulsa el partido Acci\u00f3n Nacional.<\/div>\n<div><\/div>\n<div>\u201cSoy presidente municipal y no representante de un partido pol\u00edtico, a m\u00ed me corresponde vigilar las condiciones de apertura y transparencia por lo que estaremos empe\u00f1ados en que la voluntad de los ciudadanos en las juntas auxiliares sea respetada\u201d.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El edil de Puebla, Eduardo Rivera P\u00e9rez, asegur\u00f3 que los nuevos mandos de Tr\u00e1nsito municipal est\u00e1n a prueba pues deben demostrar que son garant\u00eda de que no habr\u00e1 corrupci\u00f3n Para el alcalde de Puebla, Eduardo Rivera P\u00e9rez, los comentarios respecto a la vinculaci\u00f3n que podr\u00eda existir entre los mandos medios que fueron relevados y los [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390742","post","type-post","status-publish","format-standard","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390742"}],"version-history":[{"count":1,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390742\/revisions"}],"predecessor-version":[{"id":428988,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390742\/revisions\/428988"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}