{"id":390745,"date":"2011-03-24T03:11:51","date_gmt":"2011-03-24T03:11:51","guid":{"rendered":"legacy-k2-2009-10814"},"modified":"2011-03-24T03:11:51","modified_gmt":"2011-03-24T03:11:51","slug":"luis-donaldo-colosio-k2-10814","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/luis-donaldo-colosio-k2-10814\/390745\/","title":{"rendered":"Luis Donaldo Colosio: El gran discurso"},"content":{"rendered":"<div>En esta columna me pareci\u00f3 importante rescatar parte del ideario de Luis Donaldo Colosio y que pronunciara aqu\u00e9l memorable 6 de marzo de 1994 en el Monumento a la Revoluci\u00f3n con motivo del 65 Aniversario del Partido Revolucionario Institucional. Despu\u00e9s de releerlo pareciera que M\u00e9xico y su partido se quedaron detenidos en el tiempo, de hecho, hasta podr\u00edamos decir que se retrocedi\u00f3 y mucho.<\/div>\n<div><\/div>\n<div>Pero no quiero influir en Usted, querido lector, por eso es que prefiero dejar a su criterio y an\u00e1lisis lo dicho hace 17 a\u00f1os -por razones de espacio es que me he permitido transcribir solo parte de ese discurso-.<\/div>\n<div><\/div>\n<div>\u201c\u2026..Aqu\u00ed est\u00e1 el PRI para mantener la paz y la estabilidad del pa\u00eds, para preservar la unidad entre los mexicanos. Aqu\u00ed est\u00e1 el PRI en pie de lucha.\u201d<\/div>\n<div><\/div>\n<div>\u201c\u2026.Pero nuestra herencia debe ser fuente de exigencia, no de complacencia ni de inmovilismo. S\u00f3lo los partidos autoritarios pretenden fundar su legitimidad en su herencia. Los partidos democr\u00e1ticos la ganamos diariamente.\u201d<\/div>\n<div><\/div>\n<div>\u201c\u2026..Hoy vivimos en la competencia y a la competencia tenemos que acudir; para hacerlo se dejan atr\u00e1s viejas pr\u00e1cticas: las de un PRI que s\u00f3lo dialogaba consigo mismo y con el gobierno, las de un partido que no ten\u00eda que realizar grandes esfuerzos para ganar.\u201d<\/div>\n<div><\/div>\n<div>\u2026..\u201dNo queremos candidatos que, al ser postulados, los primeros sorprendidos en conocer su supuesta militancia, seamos los propios pri\u00edstas.\u201d<\/div>\n<div><\/div>\n<div>\u201c\u2026..Me he encontrado con el M\u00e9xico de los justos reclamos, de los antiguos agravios y de las nuevas demandas; el M\u00e9xico de las esperanzas, el que exige respuestas, el que ya no puede esperar.\u201d<\/div>\n<div><\/div>\n<div>\u201c\u2026..Yo veo un M\u00e9xico de comunidades ind\u00edgenas, que no pueden esperar m\u00e1s a las exigencias de justicia, de dignidad y de progreso\u2026.Yo veo un M\u00e9xico de campesinos que a\u00fan no tienen las respuestas que merecen\u2026. un campo empobrecido, endeudado\u2026.. Un M\u00e9xico de trabajadores que no encuentran los empleos ni los salarios que demandan\u2026..un M\u00e9xico de j\u00f3venes que enfrentan todos los d\u00edas la dif\u00edcil realidad de la falta de empleo, que no siempre tienen a su alcance las oportunidades de educaci\u00f3n y de preparaci\u00f3n. J\u00f3venes que muchas veces se ven orillados a la delincuencia, a la drogadicci\u00f3n\u2026.un M\u00e9xico de mujeres que a\u00fan no cuentan con las oportunidades que les pertenecen\u2026. un M\u00e9xico de empresarios, de la peque\u00f1a y la mediana empresa, a veces desalentados por el burocratismo, por el mar de tr\u00e1mites, por la discrecionalidad en las autoridades\u2026.Un M\u00e9xico de maestras y de maestros, de universitarios, de investigadores, que piden reconocimiento a su vida profesional, que piden la elevaci\u00f3n de sus ingresos y condiciones m\u00e1s favorables para el rendimiento de sus frutos acad\u00e9micos\u2026..Todos ellos son las mujeres y los hombres que mucho han contribuido a la construcci\u00f3n del pa\u00eds en que vivimos y a quienes habremos de responderles.\u201d<\/div>\n<div><\/div>\n<div>\u201c\u2026..Yo veo un M\u00e9xico con hambre y con sed de justicia. Un M\u00e9xico de gente agraviada por las distorsiones que imponen a la ley quienes deber\u00edan de servirla. De mujeres y hombres afligidos por abuso de las autoridades o por la arrogancia de las oficinas gubernamentales.\u201d<\/div>\n<div><\/div>\n<div>\u201c\u2026..Veo a ciudadanos angustiados por la falta de seguridad, ciudadanos que merecen mejores servicios y gobiernos que les cumplan. Ciudadanos que a\u00fan no tienen fincada en el futuro la derrota; son ciudadanos que tienen esperanza y que est\u00e1n dispuestos a sumar su esfuerzo para alcanzar el progreso.\u201d<\/div>\n<div><\/div>\n<div>\u201c\u2026.\u00a1Es la hora de cerrarle el paso al influyentismo, a la corrupci\u00f3n y a la impunidad!\u201d<\/div>\n<div><\/div>\n<div>\u201c\u2026..Queremos un M\u00e9xico unido, queremos un M\u00e9xico fuerte, queremos un M\u00e9xico soberano. Un M\u00e9xico de libertades, un M\u00e9xico con paz, porque son amplios los cauces de la democracia y de la justicia. Hay sitio para todos en el M\u00e9xico por el que luchamos afanosamente\u201d.<\/div>\n<div><\/div>\n<div>Tanto en el PRI como en M\u00e9xico siguen como pendientes la democracia, la buena pol\u00edtica, la lucha contra la corrupci\u00f3n y la impunidad, la participaci\u00f3n ciudadana y la transparencia, en fin, mucho por hacer y pocos que quieran hacerlo. Pero en tanto encontramos al valiente o los valientes, nos leemos la pr\u00f3xima semana\u2026\u2026\u2026\u2026..<\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>En esta columna me pareci\u00f3 importante rescatar parte del ideario de Luis Donaldo Colosio y que pronunciara aqu\u00e9l memorable 6 de marzo de 1994 en el Monumento a la Revoluci\u00f3n con motivo del 65 Aniversario del Partido Revolucionario Institucional. Despu\u00e9s de releerlo pareciera que M\u00e9xico y su partido se quedaron detenidos en el tiempo, de [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":422590,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390745","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390745"}],"version-history":[{"count":0,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390745\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media\/422590"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}