{"id":390746,"date":"2011-03-24T03:30:01","date_gmt":"2011-03-24T03:30:01","guid":{"rendered":"legacy-k2-2009-10815"},"modified":"2011-03-24T03:30:01","modified_gmt":"2011-03-24T03:30:01","slug":"4-mujeres-en-proceso-judicial-por-abortar-en-la-capital-de-puebla-k2-10815","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/4-mujeres-en-proceso-judicial-por-abortar-en-la-capital-de-puebla-k2-10815\/390746\/","title":{"rendered":"4 mujeres en proceso judicial por abortar en la capital de Puebla"},"content":{"rendered":"<div>La regidora pri\u00edsta y ex titular del Instituto Municipal de las Mujeres, Sandra Montalvo, critic\u00f3 que los diputados se nieguen a discutir la despenalizaci\u00f3n del aborto cuando el a\u00f1o pasado cuatro mujeres enfrentaban procesos judiciales por ello<\/div>\n<div>La regidora del PRI, Sandra Montalvo, se pronunci\u00f3 en contra de la postura que asumieron los legisladores tanto de las diferentes fracciones, salvo Convergencia, por cerrarle la puerta a temas como la despenalizaci\u00f3n del aborto y la ley de sociedades de convivencia en la conformaci\u00f3n de la agenda legislativa que presentaron este martes.<\/div>\n<div><\/div>\n<div>Manifest\u00f3 que las declaraciones del l\u00edder del Congreso, Guillermo Ar\u00e9chiga Santamar\u00eda, respecto a que Puebla no estaba preparada para discutir esos temas, son lamentables y m\u00e1s en su posici\u00f3n de presidente del \u00f3rgano legislativo, pero tambi\u00e9n como l\u00edder de maestros.<\/div>\n<div><\/div>\n<div>Record\u00f3 que hasta hace un a\u00f1o, el Instituto Municipal de las Mujeres ten\u00eda documentados al menos cuatro casos de mujeres que enfrentaban un proceso judicial, despu\u00e9s de que fueran denunciadas por m\u00e9dicos que salvaron sus vidas tras practicarse un aborto en p\u00e9simas condiciones.<\/div>\n<div><\/div>\n<div>En tanto, el coordinador de los regidores del PAN, Mat\u00edas Rivero, evadi\u00f3 el tema al argumentar que esos temas est\u00e1n fuera de su competencia y por lo tanto no merec\u00edan su opini\u00f3n. Por su parte, el regidor del PRD David M\u00e9ndez hizo mutis ante estos mismos cuestionamientos sin que fijara una postura.<\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La regidora pri\u00edsta y ex titular del Instituto Municipal de las Mujeres, Sandra Montalvo, critic\u00f3 que los diputados se nieguen a discutir la despenalizaci\u00f3n del aborto cuando el a\u00f1o pasado cuatro mujeres enfrentaban procesos judiciales por ello La regidora del PRI, Sandra Montalvo, se pronunci\u00f3 en contra de la postura que asumieron los legisladores tanto [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":422589,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390746"}],"version-history":[{"count":0,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390746\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media\/422589"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}