{"id":390758,"date":"2011-03-24T14:20:46","date_gmt":"2011-03-24T14:20:46","guid":{"rendered":"http:\/\/legacy-k2-2009-10827"},"modified":"2026-03-27T18:07:02","modified_gmt":"2026-03-28T00:07:02","slug":"vazquez-mota-de-llegar-a-los-pinos-acabara-con-elba-esther-gordillo-k2-10827","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/vazquez-mota-de-llegar-a-los-pinos-acabara-con-elba-esther-gordillo-k2-10827\/390758\/","title":{"rendered":"V\u00e1zquez Mota: de llegar a Los Pinos, acabar\u00e1 con Elba Esther Gordillo"},"content":{"rendered":"<p>Charlaba Josefina V\u00e1zquez Mota con estudiantes de la Universidad Iberoamericana cuando alguno le pregunt\u00f3 cu\u00e1l hab\u00eda sido su momento pol\u00edtico m\u00e1s dif\u00edcil.<\/p>\n<p>La respuesta de la coordinadora de los diputados panistas en San L\u00e1zaro era previsible: cuando estuvo al frente de la secretar\u00eda de Educaci\u00f3n P\u00fablica \u2013al inicio de este sexenio\u2013, por sus \u201croces\u201d con Elba Esther Gordillo, la lideresa del Sindicato Nacional de Trabajadores de la Educaci\u00f3n.<\/p>\n<p>La pregunta consiguiente no tard\u00f3 en llegar: \u00bfSi llegara a la Presidencia de la Rep\u00fablica remover\u00eda a Elba Esther?<\/p>\n<p>La respuesta de V\u00e1zquez Mota, m\u00e1s acorde a la situaci\u00f3n que vive Elba Esther hoy en d\u00eda \u2013pues su liderazgo de la maestra hoy en el SNTE se asemeja mucho m\u00e1s a la posici\u00f3n de \u201cl\u00edder moral\u201d del sindicato petrolero que viv\u00eda Joaqu\u00edn Hern\u00e1ndez Galicia en el sexenio de Carlos Salinas de Gortari\u2013, lleg\u00f3 para asombro de no pocos de los asistentes:<\/p>\n<p>Record\u00f3, precisamente, lo que hizo Salinas para defenestrar a \u201cla Quina\u201d. En un momento dado, dijo, se deben tomar decisiones importantes, pues de no hacerlo \u201cvamos a seguir administrando la inercia\u201d.<\/p>\n<p>\u00bfF\u00e1cil? Obviamente no. \u201cSe requiere valor\u201d para tomar ese tipo de decisiones, reconoci\u00f3. Y todav\u00eda agreg\u00f3: \u201cCr\u00e9anme, yo s\u00e9 por qu\u00e9 se los digo; se requiere valor y estar muy bien acompa\u00f1ado\u201d.<\/p>\n<p>Sus palabras dejaban ver entre l\u00edneas que para tomar una decisi\u00f3n como esa: arremeter contra Elba Esther Gordillo, o como lo fue en su caso contra \u201cLa Quina\u201d, graves amenazas se interpon\u00edan. No s\u00f3lo a nivel pol\u00edtico, incluso personal.<\/p>\n<p>Algo debe haber vivido do\u00f1a Jose en su paso por la SEP que la hac\u00eda expresarse de esta manera frente a los j\u00f3venes de la Ibero. Cosas que seguramente van m\u00e1s all\u00e1 de los enfrentamientos p\u00fablicos que conocimos entre ella y la dirigente magisterial, como cuando la maestra ofreci\u00f3 una entrevista desde la isla Coronado y declar\u00f3 contundentemente que V\u00e1zquez Mota era \u201cuna ignorante\u201d del tema educativo.<\/p>\n<p>La diputada panista redonde\u00f3&#160; el tema asegurando que de llegar a Los Pinos acabar\u00eda con los liderazgos gremiales obsoletos y los limpiar\u00eda a fondo.<\/p>\n<p>Arriesgadas declaraciones \u2013aunque no le falte raz\u00f3n\u2013, para alguien requiere apoyos pol\u00edticos rumbo a una elecci\u00f3n presidencial. S\u00f3lo hay que recordar el costo que le signific\u00f3 a Andr\u00e9s Manuel L\u00f3pez Obrador en 2006 su desd\u00e9n a la lideresa magisterial.<\/p>\n<p>Este lance de Josefina V\u00e1zquez Mota frente a Elba Esther, lo que nos dice hoy es que la panista est\u00e1&#160; apostando fuerte \u2013su resto\u2014por lograr la candidatura presidencial de su partido y la mism\u00edsima presidencia de la Rep\u00fablica.<br \/>\n&#160;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Charlaba Josefina V\u00e1zquez Mota con estudiantes de la Universidad Iberoamericana cuando alguno le pregunt\u00f3 cu\u00e1l hab\u00eda sido su momento pol\u00edtico m\u00e1s dif\u00edcil. La respuesta de la coordinadora de los diputados panistas en San L\u00e1zaro era previsible: cuando estuvo al frente de la secretar\u00eda de Educaci\u00f3n P\u00fablica \u2013al inicio de este sexenio\u2013, por sus \u201croces\u201d con [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390758","post","type-post","status-publish","format-standard","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390758"}],"version-history":[{"count":1,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390758\/revisions"}],"predecessor-version":[{"id":429000,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390758\/revisions\/429000"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}