{"id":390768,"date":"2011-03-24T20:39:14","date_gmt":"2011-03-24T20:39:14","guid":{"rendered":"http:\/\/legacy-k2-2009-10837"},"modified":"2026-03-27T18:07:05","modified_gmt":"2026-03-28T00:07:05","slug":"tribunal-electoral-de-puebla-multa-a-partidos-por-campanas-de-hace-cuatro-anos-k2-10837","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/tribunal-electoral-de-puebla-multa-a-partidos-por-campanas-de-hace-cuatro-anos-k2-10837\/390768\/","title":{"rendered":"Tribunal Electoral de Puebla multa a partidos por campa\u00f1as de hace cuatro a\u00f1os"},"content":{"rendered":"<p>El Tribunal Electoral del Estado encontr\u00f3 \u201cfaltas leves\u201d en las campa\u00f1as de 2007 por lo que aplic\u00f3 multas m\u00ednimas a los partidos pol\u00edticos\u00a0<\/p>\n<p> \u00a0En sesi\u00f3n p\u00fablica celebrada este d\u00eda, el Pleno del Tribunal Electoral del Estado de Puebla, determin\u00f3 sancionar con multas econ\u00f3micas a los Partidos Pol\u00edticos Verde Ecologista de M\u00e9xico, Esperanza Ciudadana, de la Revoluci\u00f3n Democr\u00e1tica, Nueva Alianza y Convergencia por incurrir en faltas leves en los informes anuales sobre la aplicaci\u00f3n de sus reg\u00edmenes de financiamiento de los a\u00f1os 2007 y 2008.\u00a0 <\/p>\n<p>El Presidente del \u00f3rgano jurisdiccional doctor Antonio Oropeza Barbosa y los Magistrados Gabriel Gonz\u00e1lez Alegr\u00eda y Reynaldo Lazcano Fern\u00e1ndez,\u00a0 resolvieron ocho asuntos especiales relativos al ejercicio del financiamiento p\u00fablico y privado correspondientes a los periodos del primero de Enero al 31 de Diciembre del a\u00f1o 2007 y del primero de Enero al 31 de Diciembre del a\u00f1o 2008.<\/p>\n<p>La autoridad en materia electoral del Estado determin\u00f3 calificar de leves las faltas de los partidos pol\u00edticos\u00a0\u00a0 Verde Ecologista de M\u00e9xico, Esperanza Ciudadana, de la Revoluci\u00f3n Democr\u00e1tica, Convergencia y Nueva Alianza a los que sancionaron con multas que van de los 300 a los 600 d\u00edas de Salario M\u00ednimo vigente en la fecha en que los Institutos Pol\u00edticos incurrieron en las infracciones.<\/p>\n<p>&nbsp;<\/p>\n<p>El presidente del Tribunal Electoral del Estado de Puebla, Antonio Oropeza Barbosa, inform\u00f3 que el pleno de dicho \u00f3rgano resolvi\u00f3 ocho asuntos especiales relacionados con la revisi\u00f3n al financiamiento de los partidos pol\u00edticos de los cuales cinco fueron sancionados econ\u00f3micamente.<\/p>\n<p>Indic\u00f3 que la multa al Partido Verde Ecologista de M\u00e9xico (PVEM) fue por 43 mil 980 pesos de la Revoluci\u00f3n Democr\u00e1tica (PRD) con 14 mil 850 pesos, Nueva Alianza con 19 mil 850 pesos y Convergencia con 14 mil 850 pesos.<\/p>\n<p>En tanto que al Partido Esperanza Ciudadana el cual desapareci\u00f3 en el pasado proceso electoral de 2007 al no reunir el porcentaje m\u00ednimo de votos la sanci\u00f3n econ\u00f3mica es de 14 mil 280 pesos.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Tribunal Electoral del Estado encontr\u00f3 \u201cfaltas leves\u201d en las campa\u00f1as de 2007 por lo que aplic\u00f3 multas m\u00ednimas a los partidos pol\u00edticos\u00a0 \u00a0En sesi\u00f3n p\u00fablica celebrada este d\u00eda, el Pleno del Tribunal Electoral del Estado de Puebla, determin\u00f3 sancionar con multas econ\u00f3micas a los Partidos Pol\u00edticos Verde Ecologista de M\u00e9xico, Esperanza Ciudadana, de la [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390768","post","type-post","status-publish","format-standard","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390768"}],"version-history":[{"count":1,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390768\/revisions"}],"predecessor-version":[{"id":429009,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390768\/revisions\/429009"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}