{"id":390783,"date":"2011-03-25T00:58:44","date_gmt":"2011-03-25T00:58:44","guid":{"rendered":"http:\/\/legacy-k2-2009-10852"},"modified":"2026-03-27T18:07:10","modified_gmt":"2026-03-28T00:07:10","slug":"comuna-reactivara-los-centros-de-desarrollo-comunitario-k2-10852","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/comuna-reactivara-los-centros-de-desarrollo-comunitario-k2-10852\/390783\/","title":{"rendered":"Comuna reactivar\u00e1 los Centros de Desarrollo Comunitario"},"content":{"rendered":"<div>Los siete Centros de Desarrollo Comunitarios (CDC) que existen en la capital poblana ser\u00e1n reactivados por el Ayuntamiento, a trav\u00e9s de diversas estrategias y trabajo interinstitucional de las dependencias municipales, para responder a las necesidades de los sectores de la sociedad que atienden.<\/div>\n<div>\u00a0<\/div>\n<div>El presidente municipal de Puebla, Eduardo Rivera P\u00e9rez, acudi\u00f3 a la zona norponiente de la capital, en la Unidad Habitacional Solidaridad Nacional, donde ante los vecinos del lugar ofreci\u00f3 servicios de calidad de la mano de diversas dependencias que conforman la administraci\u00f3n local.<\/div>\n<div>\u00a0<\/div>\n<div>\u201cEs importante el trabajo en equipo y venimos aqu\u00ed ante ustedes en donde se requiere chambear, escuchar sus peticiones, dar respuestas concretas y venimos a servirles, porque ustedes nos contrataron para chambear y trabajar duro en estos a\u00f1os, y no puede haber \u00e1reas de la administraci\u00f3n p\u00fablica divorciadas, cada quien queriendo hacer por un lado su chamba\u201d, explic\u00f3.<\/div>\n<div>\u00a0<\/div>\n<div>Muchos de estos CDC han estado en el olvido y la atenci\u00f3n brindada a los ciudadanos en ocasiones no ha sido la adecuada, es por ello que durante esta administraci\u00f3n se ha propuesto rescatarlos, para que los habitantes cuenten con servicios de calidad cerca de sus localidades.<\/div>\n<div>\u00a0<\/div>\n<div>\u201cNos hemos propuesto que los servicios que se ofrezcan sean eficientes, el trabajo que se hace sea de calidad, los CDC H\u00e1bitat, estamos empezados en que se mantenga, pero bien, que den atenci\u00f3n en diversas \u00e1reas, como salud, con los j\u00f3venes, los deportistas, mujeres\u201d, detall\u00f3.<\/div>\n<div>\u00a0<\/div>\n<div>Las primeras \u00e1reas que se atender\u00e1n, dijo el edil, son desarrollo social, seguridad p\u00fablica, desarrollo urbano y servicios p\u00fablicos, entre las primeras acciones ser\u00e1 la puesta en marcha del programa Colono Alerta y la construcci\u00f3n de una barda en la parte trasera del CDC para evitar robos al interior.<\/div>\n<div>\u00a0<\/div>\n<div>En su oportunidad el titular de la Secretar\u00eda de Desarrollo Social Municipal, Javier S\u00e1nchez D\u00edaz de Rivera, destac\u00f3 la importancia de estos Centros, los cuales tienen una cobertura de hasta 190 mil personas, ya que se localizan en puntos clave para abarcar varias colonias, sobre todo las de la periferia.<\/div>\n<div>\u00a0<\/div>\n<div>Los programas que se pondr\u00e1n en marcha son por parte del Instituto Municipal de las Mujeres (IMM) \u201cMujeres Emprendedoras\u201d con la aplicaci\u00f3n de talleres productivos y la impartici\u00f3n de pl\u00e1ticas con temas contra la violencia y atenci\u00f3n jur\u00eddica.<\/div>\n<div>\u00a0<\/div>\n<div>El Sistema Municipal DIF (SMDIF) ofrecer\u00e1 cursos de medicina alternativa, atenci\u00f3n en problemas de desintegraci\u00f3n familiar, talleres productivos para personas de la tercera edad, programa de Familia Fortaleza Poblana, Jornadas M\u00e9dicas y Asistenciales.<\/div>\n<div>\u00a0<\/div>\n<div>El Instituto Municipal del Deporte (IMD) comenzar\u00e1 con la puesta en marcha de las escuelas de iniciaci\u00f3n, puntos activos f\u00edsicos, la conformaci\u00f3n de ligas deportivas y diversas acciones encaminadas a fomentar el deporte.<\/div>\n<div>\u00a0<\/div>\n<div>El Instituto Municipal de Arte y Cultura (IMAC) se har\u00e1 cargo de talleres, actividades y exposiciones encaminadas a la cultura en esta Unidad Habitacional, donde los j\u00f3venes artistas pondr\u00e1n de manifiesto su talento, adem\u00e1s de realizar recorridos virtuales a museos de diversas partes del mundo.<\/div>\n<div>\u00a0<\/div>\n<div>Finalmente personal del Instituto Municipal de la Juventud (IMJ) ser\u00e1n los encargados de entregar tarjetas Poder Joven a los habitantes de esta zona, para que tengan acceso a diversas promociones, iniciar\u00e1n una campa\u00f1a para evitar las adicciones, los embarazos no deseados, violencia en el noviazgo adem\u00e1s de la implementaci\u00f3n del programa \u201c\u00c1ngeles\u201d.<\/div>\n<div>\u00a0<\/div>\n<div>Para cumplir con estos objetivos e implementar los programas, se sign\u00f3 un convenio de relanzamiento de la estrategia de los CDC, dicho documento fue firmado como testigo de honor por el edil de Puebla, Eduardo Rivera P\u00e9rez y los titulares de diversas dependencias municipales como la Presidenta del Patronato del SMDIF, Liliana Ortiz de Rivera; el director del SMDIF, Arturo Vasconcelos Rueda; la directora del IMM, Cecilia Espino Gonz\u00e1lez; del IMD, Ximena Mata Zenteno y el titular del IMJ, Emmanuel Torres Bautista. \u00a0 \u00a0\u00a0<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los siete Centros de Desarrollo Comunitarios (CDC) que existen en la capital poblana ser\u00e1n reactivados por el Ayuntamiento, a trav\u00e9s de diversas estrategias y trabajo interinstitucional de las dependencias municipales, para responder a las necesidades de los sectores de la sociedad que atienden. \u00a0 El presidente municipal de Puebla, Eduardo Rivera P\u00e9rez, acudi\u00f3 a la [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390783","post","type-post","status-publish","format-standard","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390783"}],"version-history":[{"count":1,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390783\/revisions"}],"predecessor-version":[{"id":429022,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390783\/revisions\/429022"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}