{"id":390785,"date":"2011-03-25T01:19:56","date_gmt":"2011-03-25T01:19:56","guid":{"rendered":"http:\/\/legacy-k2-2009-10855"},"modified":"2026-03-27T18:07:11","modified_gmt":"2026-03-28T00:07:11","slug":"pierdete-puebla-guia-del-ocio-k2-10855","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/pierdete-puebla-guia-del-ocio-k2-10855\/390785\/","title":{"rendered":"Pi\u00e9rdete Puebla. Gu\u00eda del Ocio"},"content":{"rendered":"<p>Grandes conciertos y estrenos en el cine te esperan este fin de semana en Puebla<\/p>\n<p><strong>CINE<\/strong><\/p>\n<p><strong>La Otra Familia (M\u00e9xico, 2011) <\/strong><\/p>\n<p>  Al ser abandonado durante 3 d\u00edas por su madre adicta al crack, Hendrix, un peque\u00f1o de 7 a\u00f1os, es rescatado por una amiga y encargado a una pareja homosexual. Su madre es forzada a entrar en rehabilitaci\u00f3n, mientras su amante, un traficante de drogas, ve en \u00e9l un redituable negocio si lo vende a un matrimonio que acaba de perder a su beb\u00e9. La madre huye de la cl\u00ednica para recuperarlo a como d\u00e9 lugar; por su parte, las autoridades pretenden protegerlo ingres\u00e1ndolo en un orfanatorio. Al parecer, todo mundo puede opinar sobre el futuro del ni\u00f1o, pero\u2026 \u00bfQu\u00e9 es lo que realmente conviene a Hendrix? \u00bfQui\u00e9n puede decidir cu\u00e1l es el hogar perfecto?   G\u00e9nero: Drama Clasificaci\u00f3n:  B15 Duraci\u00f3n: 130 min. Director: Gustavo Loza Actores: Jorge Salinas, Luis Roberto Guzm\u00e1n, Ana Serradilla, Nailea Norvind, Bruno Loza. Gui\u00f3n: Gustavo Loza   <\/p>\n<div><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\" width=\"480\" height=\"390\"><param name=\"width\" value=\"480\" \/><param name=\"height\" value=\"390\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/S3a-KOOrbOI?fs=1&#038;hl=es_ES\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed type=\"application\/x-shockwave-flash\" width=\"480\" height=\"390\" src=\"http:\/\/www.youtube.com\/v\/S3a-KOOrbOI?fs=1&#038;hl=es_ES\" allowscriptaccess=\"always\" allowfullscreen=\"true\"><\/embed><\/object><\/div>\n<p><strong>     TEATRO <\/strong><\/p>\n<p><strong>A Vivir <\/strong><\/p>\n<p>  \u00bfCu\u00e1ntas veces nos hemos preguntado si vivimos la vida que queremos o la que imaginamos? La respuesta es dif\u00edcil de encontrar, ya que en pocas ocasiones somos capaces de enfrentarnos a nuestros miedos y frustraciones que han sido determinantes en el rumbo a seguir en nuestro camino hacia la felicidad. A Vivir es un mon\u00f3logo escrito y actuado por Od\u00edn Dupeyron, que har\u00e1 llorar y re\u00edr al espectador, para luego sumergirlo en una catarsis de reflexi\u00f3n sobre la b\u00fasqueda de la felicidad en nuestra vida.   Fecha: Jueves 24 de marzo Hora: 20 horas Lugar: Complejo Cultural Universitario (V\u00eda Atlixc\u00e1yotl n\u00famero 2499, San Andr\u00e9s Cholula) Costos: Desde $350 pesos     <\/p>\n<div><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\" width=\"480\" height=\"390\"><param name=\"width\" value=\"480\" \/><param name=\"height\" value=\"390\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/U_ekpJoXOeA?fs=1&#038;hl=es_ES\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed type=\"application\/x-shockwave-flash\" width=\"480\" height=\"390\" src=\"http:\/\/www.youtube.com\/v\/U_ekpJoXOeA?fs=1&#038;hl=es_ES\" allowscriptaccess=\"always\" allowfullscreen=\"true\"><\/embed><\/object><\/div>\n<p><strong>M\u00daSICA <\/strong><\/p>\n<p><strong>Baila <\/strong><\/p>\n<p><strong>Lost Acapulco <\/strong><\/p>\n<p>  La banda de surf acapulque\u00f1a, interpretar\u00e1 en Puebla sus m\u00e1s grandes \u00e9xitos, acompada de las bandas invitadas: Los Santisimos Snorkels y The Antropolokos. Esta noche no podr\u00e1s perderte la mejor m\u00fasica slam del pa\u00eds.   Fecha: Viernes 25 de marzo Hora: 20 horas Lugar: Red House (Circuito Juan Pablo II n\u00famero 2715) Costo: $80 y $100 pesos<\/p>\n<div><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\" width=\"480\" height=\"390\"><param name=\"width\" value=\"480\" \/><param name=\"height\" value=\"390\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/YIkZD8WpznE?fs=1&#038;hl=es_ES\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed type=\"application\/x-shockwave-flash\" width=\"480\" height=\"390\" src=\"http:\/\/www.youtube.com\/v\/YIkZD8WpznE?fs=1&#038;hl=es_ES\" allowscriptaccess=\"always\" allowfullscreen=\"true\"><\/embed><\/object><\/div>\n<p><strong>     Escucha<\/strong><\/p>\n<p><strong> Los Tigres del Norte <\/strong><\/p>\n<p>La mejor m\u00fasica norte\u00f1a del pa\u00eds ser\u00e1 amenizada por las bandas: Los Marios, Grupo Taxi, los Titanes de Durango, Duelo y el Conjunto Primavera.   Fecha: S\u00e1bado 26 de marzo Hora: 21 horas Lugar: Explanada del estadio Cuauht\u00e9moc Costo: Preventa: $150 pesos   <\/p>\n<div><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\" width=\"480\" height=\"390\"><param name=\"width\" value=\"480\" \/><param name=\"height\" value=\"390\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/tKQwOuTiY-A?fs=1&#038;hl=es_ES\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed type=\"application\/x-shockwave-flash\" width=\"480\" height=\"390\" src=\"http:\/\/www.youtube.com\/v\/tKQwOuTiY-A?fs=1&#038;hl=es_ES\" allowscriptaccess=\"always\" allowfullscreen=\"true\"><\/embed><\/object><\/div>\n<p><strong>     Canta <\/strong><\/p>\n<p><strong>Luis Miguel Tour M\u00e9xico 2011 <\/strong><\/p>\n<p>  La \u00faltima producci\u00f3n discogr\u00e1fica del llamado Sol de M\u00e9xico, &#8220;Labios de Miel&#8221;, sonar\u00e1 en Puebla, junto al nuevo sencillo \u201cMujer de Fuego\u201d y sus nuevas canciones: Tres palabras, Ella es as\u00ed, No existen l\u00edmites, Siento, Lo que queda de m\u00ed, y Es por ti.   Fecha: Martes 29 de marzo Hora: Acceso a las 19 horas Lugar: Canchas de Futbol de la Ibero Puebla Costo: Desde $400 a $3 mil pesos     <\/p>\n<div><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\" width=\"480\" height=\"390\"><param name=\"width\" value=\"480\" \/><param name=\"height\" value=\"390\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/Pjc23vy8Bhc?fs=1&#038;hl=es_ES\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed type=\"application\/x-shockwave-flash\" width=\"480\" height=\"390\" src=\"http:\/\/www.youtube.com\/v\/Pjc23vy8Bhc?fs=1&#038;hl=es_ES\" allowscriptaccess=\"always\" allowfullscreen=\"true\"><\/embed><\/object><\/div>\n<p><strong>     Disfruta <\/strong><\/p>\n<p><strong>Abba Mania &#038; Bee Gees <\/strong><\/p>\n<p>  Con la licencia de los grupos originales, los int\u00e9rpretes de estas dos bandas han dado la vuelta al mundo por su esp\u00edritu y m\u00fasica, principalmente en Londres, Roma, Par\u00eds, Tokio, Luxemburgo, Atenas, M\u00f3naco, Pek\u00edn, New York, Los \u00c1ngeles, Chicago, Dallas, Atlanta, Washington DC, entre otros.   Fecha: Mi\u00e9rcoles 30 de marzo Hora: 20:30 horas Lugar: Complejo Cultural Universitario (V\u00eda Atlixc\u00e1yotl n\u00famero 2499, San Andr\u00e9s Cholula, Puebla) Costos: Desde $300 pesos   <\/p>\n<div><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\" width=\"480\" height=\"390\"><param name=\"width\" value=\"480\" \/><param name=\"height\" value=\"390\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/prt42YzFeb0?fs=1&#038;hl=es_ES\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed type=\"application\/x-shockwave-flash\" width=\"480\" height=\"390\" src=\"http:\/\/www.youtube.com\/v\/prt42YzFeb0?fs=1&#038;hl=es_ES\" allowscriptaccess=\"always\" allowfullscreen=\"true\"><\/embed><\/object><\/div>\n<p><strong>     EXPOSICIONES <\/strong><\/p>\n<p><strong>XXIV Feria Nacional del Libro Puebla 2011 <\/strong><\/p>\n<p>  Esta feria reunir\u00e1 a editoriales comerciales y universitarias, con la intenci\u00f3n de difundir la cultura y el h\u00e1bito de la lectura, a trav\u00e9s de presentaciones de libros, conferencias, as\u00ed como actividades complementarias de m\u00fasica, teatro y danza.   Fecha: Domingo 27 de marzo Hora: Desde las 10 de la ma\u00f1ana Lugar: Complejo Cultural Universitario (V\u00eda Atlixc\u00e1yotl n\u00famero 2499, San Andr\u00e9s Cholula) Costo: Entrada Libre     <\/p>\n<div><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\" width=\"480\" height=\"390\"><param name=\"width\" value=\"480\" \/><param name=\"height\" value=\"390\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/8jPWqPq3zLo?fs=1&#038;hl=es_ES\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed type=\"application\/x-shockwave-flash\" width=\"480\" height=\"390\" src=\"http:\/\/www.youtube.com\/v\/8jPWqPq3zLo?fs=1&#038;hl=es_ES\" allowscriptaccess=\"always\" allowfullscreen=\"true\"><\/embed><\/object><\/div>\n<p><strong>     ECOLOG\u00cdA <\/strong><\/p>\n<p><strong>La Hora del Planeta <\/strong><\/p>\n<p>  La mayor campa\u00f1a de movilizaci\u00f3n simb\u00f3lica para luchar contra el cambio clim\u00e1tico llegar\u00e1 M\u00e9xico este s\u00e1bado 26 de marzo a las 20:30 horas, cuando empresas, instituciones, organizaciones, gobiernos y ciudadanos apagar\u00e1n la luz durante una hora y se comprometer\u00e1n a lo largo del a\u00f1o con una acci\u00f3n que haga la diferencia.   De acuerdo con los convocantes, en 2010 m\u00e1s de 128 pa\u00edses y 4 mil 616 ciudades apagaron la luz por 60 minutos. Si desea m\u00e1s informaci\u00f3n visite:http:\/\/www.wwf.org.mx\/la-hora-del-planeta\/     <\/p>\n<div><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\" width=\"640\" height=\"390\"><param name=\"width\" value=\"640\" \/><param name=\"height\" value=\"390\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/z3GRK0B4i6s?fs=1&#038;hl=es_ES\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed type=\"application\/x-shockwave-flash\" width=\"640\" height=\"390\" src=\"http:\/\/www.youtube.com\/v\/z3GRK0B4i6s?fs=1&#038;hl=es_ES\" allowscriptaccess=\"always\" allowfullscreen=\"true\"><\/embed><\/object><\/div>\n<p><strong>   NI\u00d1OS <\/strong><\/p>\n<p><strong>Gnomeo &#038; Juliet (Reino Unido, 2011) <\/strong><\/p>\n<p>  El maravilloso cuento de William Shakespeare totalmente divertido y con una imagen renovada. Experimentar\u00e1s una transformaci\u00f3n disparatada y tremendamente divertida. La historia narra los conflictos entre los gnomos de jardines enemigos quienes disputan su territorio y el amor de Julieta, en emocionantes carreras podadoras de pasto y un sinf\u00edn de pruebas \u00bfPodr\u00e1 esta joven pareja encontrar la felicidad eterna?   G\u00e9nero: Comedia\/Animaci\u00f3n Clasificaci\u00f3n: AA Duraci\u00f3n: 84 min. Director: Kelly Asbury Actores\/Voces: James McAvoy, Emily Blunt, Jason Statham, Michael Caine, Maggie Smith. Gui\u00f3n: Rob Sprackling, John R. Smith.     <\/p>\n<div><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\" width=\"640\" height=\"390\"><param name=\"width\" value=\"640\" \/><param name=\"height\" value=\"390\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/y85NeNJIva4?fs=1&#038;hl=es_ES\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed type=\"application\/x-shockwave-flash\" width=\"640\" height=\"390\" src=\"http:\/\/www.youtube.com\/v\/y85NeNJIva4?fs=1&#038;hl=es_ES\" allowscriptaccess=\"always\" allowfullscreen=\"true\"><\/embed><\/object><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Grandes conciertos y estrenos en el cine te esperan este fin de semana en Puebla CINE La Otra Familia (M\u00e9xico, 2011) Al ser abandonado durante 3 d\u00edas por su madre adicta al crack, Hendrix, un peque\u00f1o de 7 a\u00f1os, es rescatado por una amiga y encargado a una pareja homosexual. Su madre es forzada a [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":422577,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390785"}],"version-history":[{"count":1,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390785\/revisions"}],"predecessor-version":[{"id":429024,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390785\/revisions\/429024"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media\/422577"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}