{"id":390810,"date":"2011-03-25T13:33:13","date_gmt":"2011-03-25T13:33:13","guid":{"rendered":"legacy-k2-2009-10880"},"modified":"2011-03-25T13:33:13","modified_gmt":"2011-03-25T13:33:13","slug":"diputado-del-prd-involucrado-en-10-casos-de-abuso-contra-menores-k2-10880","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/diputado-del-prd-involucrado-en-10-casos-de-abuso-contra-menores-k2-10880\/390810\/","title":{"rendered":"Diputado del PRD involucrado en 10 casos de abuso contra menores"},"content":{"rendered":"<p>El ex diputado del PRD en el Distrito Federal, Juan Bustos Pascual, podr\u00eda estar involucrado en 10 casos m\u00e1s de abuso contra menores de edad.<\/p>\n<p>El legislador del PRI, Cristian Vargas, asegur\u00f3 que a su oficina han llegado 10 cartas de j\u00f3venes, en su mayor\u00eda estudiantes de la preparatoria Justo Sierra, que acusan a Bustos Pascual de haber abusado sexualmente de ellas.<\/p>\n<p>\u201cLlegaron hasta la oficina del Z\u00f3calo cartas pidiendo el anonimato, pidi\u00e9ndonos ayuda porque las tienen amenazadas, de que si ellas presentan una denuncia, \u00e9l las va a desaparecer\u201d, dijo el legislador.<\/p>\n<p>Desde el martes por la noche, Grupo Imagen Multimedia inform\u00f3 que el pasado 17 de marzo, Mar\u00eda Guadalupe (quien omite sus apellidos por seguridad) present\u00f3 una denuncia en contra del director ejecutivo de Fomento Cooperativo de la GAM. Acusa que invit\u00f3 a su hija de 12 a\u00f1os a Acapulco y la viol\u00f3. El mi\u00e9rcoles, la Procuradur\u00eda General de Justicia del DF inform\u00f3 que cit\u00f3 a declarar al funcionario.<\/p>\n<p>Horas despu\u00e9s, ese mismo d\u00eda, la delegaci\u00f3n se deslind\u00f3 de Bustos y dijo que el 15 de marzo su funcionario hab\u00eda renunciado para atender la demanda penal en su contra.<\/p>\n<p>Copias de algunas de estas cartas enviadas a las oficinas de Cristian Vargas dicen que el ex diputado o algunos de sus colaboradores acud\u00edan a una escuela frecuentemente a contactar estudiantes.<\/p>\n<p>Les promet\u00edan empleo o las invitaban a fiestas.<\/p>\n<p>\u201cAlgunas veces asistimos porque nos ofrec\u00eda dinero y dec\u00eda que s\u00f3lo era como acompa\u00f1antes, pero ya estando en las fiestas nos obligaba a tomar bebidas alcoh\u00f3licas y a tener relaciones sexuales con \u00e9l, y si no cumpl\u00edamos nos amenazaba\u201d, dice una de las cartas enviada por una menor de 14 a\u00f1os.<\/p>\n<p>El diputado priista dijo que ya pidi\u00f3 a estas j\u00f3venes presentar las denuncias pertinentes ante el Ministerio P\u00fablico, ya que hasta el momento s\u00f3lo existe una en contra del ex funcionario capitalino.<\/p>\n<p>\u00c9ste fue tema de discusi\u00f3n entre los diputados del DF, ya que durante la sesi\u00f3n de ayer, Vargas present\u00f3 un punto de acuerdo para pedir a la Procuradur\u00eda General de Justicia del DF investigar a fondo este caso, brinde protecci\u00f3n a las afectadas y env\u00ede un informe detallado de la investigaci\u00f3n.<\/p>\n<p>\u201cNo importa de qu\u00e9 partido sea, pero con lo que acabo de leer y muchas m\u00e1s, dan ganas de llorar\u201d, dijo Vargas.<br \/>\n&#160;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ex diputado del PRD en el Distrito Federal, Juan Bustos Pascual, podr\u00eda estar involucrado en 10 casos m\u00e1s de abuso contra menores de edad. El legislador del PRI, Cristian Vargas, asegur\u00f3 que a su oficina han llegado 10 cartas de j\u00f3venes, en su mayor\u00eda estudiantes de la preparatoria Justo Sierra, que acusan a Bustos [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390810","post","type-post","status-publish","format-standard","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390810"}],"version-history":[{"count":0,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390810\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}