{"id":390834,"date":"2011-03-26T01:27:51","date_gmt":"2011-03-26T01:27:51","guid":{"rendered":"http:\/\/legacy-k2-2009-10906"},"modified":"2026-03-27T18:07:23","modified_gmt":"2026-03-28T00:07:23","slug":"cuatro-muertos-dejo-tragica-volcadura-en-la-calzada-zaragoza-k2-10906","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/cuatro-muertos-dejo-tragica-volcadura-en-la-calzada-zaragoza-k2-10906\/390834\/","title":{"rendered":"Cuatro muertos dej\u00f3 tr\u00e1gica volcadura en la Calzada Zaragoza"},"content":{"rendered":"<p>Esta tarde se registr\u00f3 un tr\u00e1gico accidente sobre la Calzada Zaragoza, con direcci\u00f3n al norte de la ciudad, dando como saldo cuatro personas muertas. Los cuerpos de emergencia aun se encuentran en el lugar realizando labores de rescate de los cuerpos prensados<\/p>\n<p><font class=\"Apple-style-span\" color=\"#FF0000\"><\/p>\n<p><\/font><\/p>\n<p>Esta tarde se registr\u00f3 un tr\u00e1gico accidente sobre la Calzada Zaragoza, con direcci\u00f3n al norte de la ciudad, dando como saldo cuatro personas muertas. Los cuerpos de emergencia aun se encuentran en el lugar realizando labores de rescate de los cuerpos prensados.\u00a0<\/p>\n<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta tarde se registr\u00f3 un tr\u00e1gico accidente sobre la Calzada Zaragoza, con direcci\u00f3n al norte de la ciudad, dando como saldo cuatro personas muertas. Los cuerpos de emergencia aun se encuentran en el lugar realizando labores de rescate de los cuerpos prensados Esta tarde se registr\u00f3 un tr\u00e1gico accidente sobre la Calzada Zaragoza, con direcci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":422559,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390834"}],"version-history":[{"count":1,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390834\/revisions"}],"predecessor-version":[{"id":429062,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390834\/revisions\/429062"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media\/422559"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}