{"id":390835,"date":"2011-03-26T01:42:34","date_gmt":"2011-03-26T01:42:34","guid":{"rendered":"legacy-k2-2009-10907"},"modified":"2011-03-26T01:42:34","modified_gmt":"2011-03-26T01:42:34","slug":"los-tigres-del-norte-conviven-con-sus-fans-poblanos-k2-10907","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/los-tigres-del-norte-conviven-con-sus-fans-poblanos-k2-10907\/390835\/","title":{"rendered":"Los Tigres del Norte conviven con sus fans poblanos"},"content":{"rendered":"<p>Los Tigres del Norte se encuentran en la capital poblana, donde aprovecharon este viernes para realizar diversos eventos donde convivieron con sus fans, previo a su presentaci\u00f3n musical este s\u00e1bado en la explanada del estadio Cuauht\u00e9moc<font class=\"Apple-style-span\" color=\"#FF0000\">\u00a0<\/font><\/p>\n<p>Los Tigres del Norte se encuentran en la capital poblana, donde aprovecharon este viernes para realizar diversos eventos donde convivieron con sus fans, previo a su presentaci\u00f3n musical este s\u00e1bado en la explanada del estadio Cuauht\u00e9moc<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los Tigres del Norte se encuentran en la capital poblana, donde aprovecharon este viernes para realizar diversos eventos donde convivieron con sus fans, previo a su presentaci\u00f3n musical este s\u00e1bado en la explanada del estadio Cuauht\u00e9moc\u00a0 Los Tigres del Norte se encuentran en la capital poblana, donde aprovecharon este viernes para realizar diversos eventos donde [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":422558,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390835","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390835"}],"version-history":[{"count":0,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390835\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media\/422558"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}