{"id":390838,"date":"2011-03-27T23:24:01","date_gmt":"2011-03-27T23:24:01","guid":{"rendered":"legacy-k2-2009-10910"},"modified":"2011-03-27T23:24:01","modified_gmt":"2011-03-27T23:24:01","slug":"natalie-portman-fue-doblada-en-cisne-negro-k2-10910","status":"publish","type":"post","link":"https:\/\/www.pueblaonline.com.mx\/archivo\/2011\/puebla\/natalie-portman-fue-doblada-en-cisne-negro-k2-10910\/390838\/","title":{"rendered":"Natalie Portman fue doblada en Cisne Negro"},"content":{"rendered":"<div>Una bailarina asegura que ella film\u00f3 las escenas de ballet en la cinta<\/div>\n<div>La revista Qui\u00e9n en su edici\u00f3n digital informa que Sarah Lane, bailarina profesional de Ballet, asegura que fue ella quien realiz\u00f3 las escenas de baile en la pel\u00edcula que le vali\u00f3 un Oscar a la actriz.<\/div>\n<div><\/div>\n<div>Todo mundo recuerda el momento en que Natalie Portman gan\u00f3 el premio Oscar como Mejor Actriz por la pel\u00edcula Back Swan, su interpretaci\u00f3n y su preparaci\u00f3n como bailarina de Ballet le dieron tan codiciada presea.<\/div>\n<div><\/div>\n<div>Sin embargo una joven de nombre Sarah Lane, bailarina de profesi\u00f3n, sale a la luz y reclama que ni siquiera Natalie le agradeci\u00f3 en su discurso de los premios de la Academia, por haber realizado las escenas de baile m\u00e1s dif\u00edciles de la cinta que la puso en la cima del \u00e9xito.<\/div>\n<div><\/div>\n<div>Sarah Lane habl\u00f3 para Dance Magazine sobre algunos de los secretos mejor guardados de la cinta cuyo argumento se basa en &#8220;El lago de los cisnes&#8221;.<\/div>\n<div>\u00a0<\/div>\n<div>Lane dijo que Natalie no aprendi\u00f3 a bailar ballet, inclus\u00f3 asegura que la realizadora de las escenas que robaron el aliento a m\u00e1s de uno, fueron obra de ella.<\/div>\n<div><\/div>\n<div>Sarah asegura que los productores le pidieron no dar entrevistas hasta despu\u00e9s de la entrega de los Oscar, por lo que ella cree que se trataba de una estrategia para que no le quitaran el premio a Portman.<\/div>\n<div><\/div>\n<div>Hasta el momento los agentes de la ganadora del Oscar no han dado ning\u00fan tipo de declaraci\u00f3n al respecto.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Una bailarina asegura que ella film\u00f3 las escenas de ballet en la cinta La revista Qui\u00e9n en su edici\u00f3n digital informa que Sarah Lane, bailarina profesional de Ballet, asegura que fue ella quien realiz\u00f3 las escenas de baile en la pel\u00edcula que le vali\u00f3 un Oscar a la actriz. Todo mundo recuerda el momento en [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":422556,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-390838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puebla","entry"],"_links":{"self":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/comments?post=390838"}],"version-history":[{"count":0,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/posts\/390838\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media\/422556"}],"wp:attachment":[{"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/media?parent=390838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/categories?post=390838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pueblaonline.com.mx\/archivo\/wp-json\/wp\/v2\/tags?post=390838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}